{"id":13814,"date":"2022-04-04T08:42:57","date_gmt":"2022-04-04T12:42:57","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=13814"},"modified":"2026-09-01T11:22:24","modified_gmt":"2026-09-01T14:22:24","slug":"boss-pedal-board-bcb-90x","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/","title":{"rendered":"Boss Pedal Board BCB-90X"},"content":{"rendered":"<ul>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\" data-number-of-phrases=\"13\">Pedalera BCB de nueva generaci\u00f3n, actualizada para configuraciones de pedales modernas<\/span> <\/span><\/li>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"2\" data-number-of-phrases=\"13\">Admite diversos rangos de pedal, como compactos BOSS, el multiefectos GT-1000CORE, pedales de las series 200 y 500, conmutadores de loops, etc.<\/span> <\/span><\/li>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"4\" data-number-of-phrases=\"13\">Plantilla de espuma de alta densidad personalizable para fijar los pedales<\/span> <\/span><\/li>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"6\" data-number-of-phrases=\"13\">Canal guia integrada para pasar los cables por debajo de la plantilla<\/span> <\/span><\/li>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"8\" data-number-of-phrases=\"13\">Dise\u00f1o moldeado ligero y resistente con tapa desmontable<\/span> <\/span><\/li>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"10\" data-number-of-phrases=\"13\">Cajas de conexi\u00f3n integradas para entrada de instrumento, salidas mono\/est\u00e9reo y alimentaci\u00f3n<\/span> <\/span><\/li>\n<li><span class=\"VIiyi\" lang=\"es\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"12\" data-number-of-phrases=\"13\">Incluye cable en cadena y adaptador PSB-1U para 10 pedales<\/span><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La BCB-90X de nueva generaci\u00f3n es una evoluci\u00f3n de la pedalera BOSS BCB-60 empleada por los m\u00fasicos durante casi dos d\u00e9cadas y ofrece mayor versatilidad para configuraciones de pedales modernas. Una plantilla personalizable te permite crear tu propia disposici\u00f3n para diversos tipos de pedales, como compactos BOSS, GT-1000CORE, pedales de las series 200 y 500, conmutadores de loops, pedales de volumen\/expresi\u00f3n, etc. La resistente construcci\u00f3n moldeada ofrece un gran aspecto, longevidad y peso ligero, mientras que las cajas integradas permiten realizar las conexiones para directo de forma r\u00e1pida y sencilla.<\/p>\n<p>4ESTBOBCB-90X<\/p>\n","protected":false},"featured_media":13815,"template":"","meta":[],"pwb-brand":[93],"product_brand":[],"product_cat":[145,878],"product_tag":[],"class_list":["post-13814","product","type-product","status-publish","has-post-thumbnail","pwb-brand-boss","product_cat-accesorios","product_cat-estuche","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boss Pedal Board BCB-90X - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boss Pedal Board BCB-90X - Music Hall\" \/>\n<meta property=\"og:description\" content=\"La BCB-90X de nueva generaci\u00f3n es una evoluci\u00f3n de la pedalera BOSS BCB-60 empleada por los m\u00fasicos durante casi dos d\u00e9cadas y ofrece mayor versatilidad para configuraciones de pedales modernas. Una plantilla personalizable te permite crear tu propia disposici\u00f3n para diversos tipos de pedales, como compactos BOSS, GT-1000CORE, pedales de las series 200 y 500, conmutadores de loops, pedales de volumen\/expresi\u00f3n, etc. La resistente construcci\u00f3n moldeada ofrece un gran aspecto, longevidad y peso ligero, mientras que las cajas integradas permiten realizar las conexiones para directo de forma r\u00e1pida y sencilla.  4ESTBOBCB-90X\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:22:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4ESTBOBCB-90X.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boss Pedal Board BCB-90X - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/","og_locale":"es_ES","og_type":"article","og_title":"Boss Pedal Board BCB-90X - Music Hall","og_description":"La BCB-90X de nueva generaci\u00f3n es una evoluci\u00f3n de la pedalera BOSS BCB-60 empleada por los m\u00fasicos durante casi dos d\u00e9cadas y ofrece mayor versatilidad para configuraciones de pedales modernas. Una plantilla personalizable te permite crear tu propia disposici\u00f3n para diversos tipos de pedales, como compactos BOSS, GT-1000CORE, pedales de las series 200 y 500, conmutadores de loops, pedales de volumen\/expresi\u00f3n, etc. La resistente construcci\u00f3n moldeada ofrece un gran aspecto, longevidad y peso ligero, mientras que las cajas integradas permiten realizar las conexiones para directo de forma r\u00e1pida y sencilla.  4ESTBOBCB-90X","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-09-01T14:22:24+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4ESTBOBCB-90X.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/","name":"Boss Pedal Board BCB-90X - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4ESTBOBCB-90X.jpg","datePublished":"2022-04-04T12:42:57+00:00","dateModified":"2026-09-01T14:22:24+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4ESTBOBCB-90X.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4ESTBOBCB-90X.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/boss-pedal-board-bcb-90x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Boss Pedal Board BCB-90X"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":93,"name":"Boss","slug":"boss"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/13814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/13815"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=13814"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=13814"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=13814"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=13814"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=13814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}