{"id":14134,"date":"2022-04-26T11:55:57","date_gmt":"2022-04-26T15:55:57","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=14134"},"modified":"2026-07-08T09:41:41","modified_gmt":"2026-07-08T12:41:41","slug":"guitarra-electroacustica-taylor-academy12e-n","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/","title":{"rendered":"Guitarra Electroac\u00fastica Taylor Academy12e-N"},"content":{"rendered":"<ul>\n<li><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\" data-number-of-phrases=\"5\"><span class=\"Q4iAWc\">Cuerdas de nailon con tono cl\u00e1sico c\u00e1lido y \u00e1gil.<\/span><\/span><\/li>\n<li><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"2\" data-number-of-phrases=\"5\"><span class=\"Q4iAWc\">La tapa de abeto macizo proporciona claridad y resonancia.<\/span><\/span><\/li>\n<li><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"4\" data-number-of-phrases=\"5\"><span class=\"Q4iAWc\">El reposabrazos tallado brinda una sensaci\u00f3n m\u00e1s c\u00f3moda.<\/span><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\" data-number-of-phrases=\"3\"><span class=\"Q4iAWc\">Dise\u00f1ado para ofrecer una opci\u00f3n c\u00f3moda y asequible para los guitarristas que buscan el sonido de las cuerdas de nailon con citas amigables para el guitarrista, Academy 12e-N ofrece un tono cl\u00e1sico \u00e1gil con una sensaci\u00f3n que es perfecta tanto para principiantes como para guitarristas experimentados.<\/span><\/span> <span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"1\" data-number-of-phrases=\"3\"><span class=\"Q4iAWc\">Construido con una tapa de abeto macizo para una proyecci\u00f3n, claridad y resonancia \u00f3ptimas, este compacto ac\u00fastico el\u00e9ctrico Grand Concert cuenta con un diapas\u00f3n redondeado y un ancho de tuerca de 1-7\/8&#8243; que proporciona un amplio espacio entre las cuerdas para tocar con los dedos sin ejercer una tensi\u00f3n indebida en la mano que se mueve.<\/span><\/span> <span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"2\" data-number-of-phrases=\"3\"><span class=\"Q4iAWc\">Y con la electr\u00f3nica ES-N incorporada y una funda ligera para protecci\u00f3n, Academy 12e-N tiene todo lo que un m\u00fasico en ciernes podr\u00eda necesitar.<\/span><\/span><\/p>\n<p>1GUETYACADEMY12E-NE<\/p>\n","protected":false},"featured_media":14135,"template":"","meta":[],"pwb-brand":[336],"product_brand":[],"product_cat":[79,4708,68],"product_tag":[],"class_list":["post-14134","product","type-product","status-publish","has-post-thumbnail","pwb-brand-taylor","product_cat-guitarras","product_cat-guitarra-electroacustica-cuerdas-de-metal","product_cat-instrumentos-musicales","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guitarra Electroac\u00fastica Taylor Academy12e-N - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guitarra Electroac\u00fastica Taylor Academy12e-N - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Dise\u00f1ado para ofrecer una opci\u00f3n c\u00f3moda y asequible para los guitarristas que buscan el sonido de las cuerdas de nailon con citas amigables para el guitarrista, Academy 12e-N ofrece un tono cl\u00e1sico \u00e1gil con una sensaci\u00f3n que es perfecta tanto para principiantes como para guitarristas experimentados. Construido con una tapa de abeto macizo para una proyecci\u00f3n, claridad y resonancia \u00f3ptimas, este compacto ac\u00fastico el\u00e9ctrico Grand Concert cuenta con un diapas\u00f3n redondeado y un ancho de tuerca de 1-7\/8&quot; que proporciona un amplio espacio entre las cuerdas para tocar con los dedos sin ejercer una tensi\u00f3n indebida en la mano que se mueve. Y con la electr\u00f3nica ES-N incorporada y una funda ligera para protecci\u00f3n, Academy 12e-N tiene todo lo que un m\u00fasico en ciernes podr\u00eda necesitar.  1GUETYACADEMY12E-NE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:41:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/1GUETYACADEMY12E-NE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guitarra Electroac\u00fastica Taylor Academy12e-N - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/","og_locale":"es_ES","og_type":"article","og_title":"Guitarra Electroac\u00fastica Taylor Academy12e-N - Music Hall","og_description":"Dise\u00f1ado para ofrecer una opci\u00f3n c\u00f3moda y asequible para los guitarristas que buscan el sonido de las cuerdas de nailon con citas amigables para el guitarrista, Academy 12e-N ofrece un tono cl\u00e1sico \u00e1gil con una sensaci\u00f3n que es perfecta tanto para principiantes como para guitarristas experimentados. Construido con una tapa de abeto macizo para una proyecci\u00f3n, claridad y resonancia \u00f3ptimas, este compacto ac\u00fastico el\u00e9ctrico Grand Concert cuenta con un diapas\u00f3n redondeado y un ancho de tuerca de 1-7\/8\" que proporciona un amplio espacio entre las cuerdas para tocar con los dedos sin ejercer una tensi\u00f3n indebida en la mano que se mueve. Y con la electr\u00f3nica ES-N incorporada y una funda ligera para protecci\u00f3n, Academy 12e-N tiene todo lo que un m\u00fasico en ciernes podr\u00eda necesitar.  1GUETYACADEMY12E-NE","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:41:41+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/1GUETYACADEMY12E-NE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/","name":"Guitarra Electroac\u00fastica Taylor Academy12e-N - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/1GUETYACADEMY12E-NE.jpg","datePublished":"2022-04-26T15:55:57+00:00","dateModified":"2026-07-08T12:41:41+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/1GUETYACADEMY12E-NE.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/1GUETYACADEMY12E-NE.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electroacustica-taylor-academy12e-n\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Guitarra Electroac\u00fastica Taylor Academy12e-N"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":336,"name":"Taylor","slug":"taylor"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/14134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/14135"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=14134"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=14134"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=14134"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=14134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=14134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}