{"id":16176,"date":"2022-09-15T20:18:30","date_gmt":"2022-09-16T00:18:30","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=16176"},"modified":"2026-07-08T09:41:53","modified_gmt":"2026-07-08T12:41:53","slug":"procesador-line-6-helix-rack","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/","title":{"rendered":"Procesador Line 6 Helix Rack"},"content":{"rendered":"<p style=\"font-weight: 400\">Procesador de guitarra multi-efecto de grado Tour.<\/p>\n<p style=\"font-weight: 400\">Salida para controlador de piso Helix Control.<\/p>\n<p style=\"font-weight: 400\">Motor de modelado HX con alimentaci\u00f3n DSP dual.<\/p>\n<p style=\"font-weight: 400\">45 amperios, 30 cabinas, 16 micr\u00f3fonos y 70 efectos.<\/p>\n<p style=\"font-weight: 400\">La edici\u00f3n del flujo de trabajo se puede dominar incre\u00edblemente r\u00e1pido.<\/p>\n<p style=\"font-weight: 400\">Pantalla LCD de 6.2 \u201c800 x 480.<\/p>\n<p style=\"font-weight: 400\">10 entradas, 12 salidas (incluidos cuatro bucles de efectos).<\/p>\n<p style=\"font-weight: 400\">Interfaz de audio USB 8 entradas \/ 8 salidas.<\/p>\n<p style=\"font-weight: 400\">Salidas de pedal de expresi\u00f3n m\u00faltiple.<\/p>\n<p style=\"font-weight: 400\">CV \/ Expresi\u00f3n.<\/p>\n<p style=\"font-weight: 400\">Conmutaci\u00f3n de amplificador externo.<\/p>\n<p style=\"font-weight: 400\">Entrada XLR.<\/p>\n<p style=\"font-weight: 400\">Salidas digitales S \/ PDIF, AES \/ EBU y L6 Link.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es un nuevo tipo de procesador de guitarra: no solo es un pedal multi-efecto de nivel tur\u00edstico que suena y se siente aut\u00e9ntico, lleva la experiencia del usuario a un nuevo nivel y puede actuar como el centro neur\u00e1lgico de todo tu equipo de guitarra.\u00a0Ya sea que pases tu tiempo en el estudio o en el escenario, Helix es el procesador de guitarra de pr\u00f3xima generaci\u00f3n que has estado esperando.<\/p>\n<p>4PEDL6HELIXRACK<\/p>\n","protected":false},"featured_media":16177,"template":"","meta":[],"pwb-brand":[462],"product_brand":[],"product_cat":[115,118],"product_tag":[],"class_list":["post-16176","product","type-product","status-publish","has-post-thumbnail","pwb-brand-line-6","product_cat-amplificadores","product_cat-efectos-guitarra","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Procesador Line 6 Helix Rack - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procesador Line 6 Helix Rack - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Es un nuevo tipo de procesador de guitarra: no solo es un pedal multi-efecto de nivel tur\u00edstico que suena y se siente aut\u00e9ntico, lleva la experiencia del usuario a un nuevo nivel y puede actuar como el centro neur\u00e1lgico de todo tu equipo de guitarra.\u00a0Ya sea que pases tu tiempo en el estudio o en el escenario, Helix es el procesador de guitarra de pr\u00f3xima generaci\u00f3n que has estado esperando.  4PEDL6HELIXRACK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:41:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/09\/4PEDL6HELIXRACK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Procesador Line 6 Helix Rack - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/","og_locale":"es_ES","og_type":"article","og_title":"Procesador Line 6 Helix Rack - Music Hall","og_description":"Es un nuevo tipo de procesador de guitarra: no solo es un pedal multi-efecto de nivel tur\u00edstico que suena y se siente aut\u00e9ntico, lleva la experiencia del usuario a un nuevo nivel y puede actuar como el centro neur\u00e1lgico de todo tu equipo de guitarra.\u00a0Ya sea que pases tu tiempo en el estudio o en el escenario, Helix es el procesador de guitarra de pr\u00f3xima generaci\u00f3n que has estado esperando.  4PEDL6HELIXRACK","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:41:53+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/09\/4PEDL6HELIXRACK.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/","name":"Procesador Line 6 Helix Rack - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/09\/4PEDL6HELIXRACK.jpg","datePublished":"2022-09-16T00:18:30+00:00","dateModified":"2026-07-08T12:41:53+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/09\/4PEDL6HELIXRACK.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/09\/4PEDL6HELIXRACK.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/procesador-line-6-helix-rack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Procesador Line 6 Helix Rack"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":462,"name":"Line 6","slug":"line-6"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/16176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/16177"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=16176"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=16176"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=16176"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=16176"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=16176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}