{"id":16915,"date":"2022-11-23T11:32:30","date_gmt":"2022-11-23T14:32:30","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=16915"},"modified":"2026-05-04T09:12:22","modified_gmt":"2026-05-04T12:12:22","slug":"monitor-estudio-krk-rokit-rp10-3-g4-par","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/","title":{"rendered":"Monitor Estudio KRK Rokit RP10-3 G4 (PAR)"},"content":{"rendered":"<h2 class=\"fx-headline fx-headline--3 fx-space-bottom--m\">Monitor de campo cercano activo de 3 v\u00edas<\/h2>\n<ul class=\"fx-list product-text__list\">\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Woofer de 10&#8243; de Kevlar<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Altavoz de medios de Kevlar de 4,5&#8243;<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Tweeter de Kevlar de 1&#8243;<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Amplificador de 300 W de clase D triamplificado<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">75 W en agudos y 150 W en graves<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Nivel m\u00e1ximo de presi\u00f3n sonora: 112 dB (SPL)<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Respuesta en frecuencia: 26 Hz &#8211; 40 kHz<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Pantalla integrada LC iluminada<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">EQ gr\u00e1fico con 25 Presets visuales (basados en DSP)<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">KRK-App con herramientas de correcci\u00f3n de sala (iOS + Android)<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Limitador Brickwall<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Posibilidad de posicionamiento en vertical y horizontal<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Conectores de entrada: Combinados XLR y Jack de 6,3 mm sim\u00e9tricos<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Medidas (Al x An x pr): 546 x 329 x 371 mm<\/span><\/li>\n<li class=\"fx-list__item list-item fx-list__item--circle\"><span class=\"fx-text fx-text--plus list-item__text\">Peso: 15,9 kg<\/span><\/li>\n<\/ul>\n<h4>Otras caracter\u00edsticas:<\/h4>\n<div class=\"a-box a-spacing-small a-color-alternate-background apm-listbox\">\n<div class=\"a-box-inner\">\n<ul class=\"a-unordered-list a-vertical\">\n<li><span class=\"a-list-item\"><span class=\"a-size-base\">Una pantalla LCD para visualizar la configuraci\u00f3n del ecualizador<\/span><\/span><\/li>\n<li><span class=\"a-list-item\"><span class=\"a-size-base\">El puerto de disparo frontal extiende la reproducci\u00f3n precisa y estrecha de graves en las frecuencias de gama baja<\/span><\/span><\/li>\n<li><span class=\"a-list-item\"><span class=\"a-size-base\">Dise\u00f1ado para garantizar el flujo de aire laminar para reducir la turbulencia de los puertos y respuesta transitoria de baja frecuencia.<\/span><\/span><\/li>\n<li><span class=\"a-list-item\"><span class=\"a-size-base\">Dise\u00f1ado con materiales de alta calidad que funcionan perfectamente con los controladores avanzados de fibra de aramida.<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El nuevo y estruendoso monitor profesional de tres amplificadores KRK ROKIT RP103 G4 (Generaci\u00f3n 4) de 10&#8243; lleva la creatividad de la m\u00fasica y el sonido a un nivel completamente nuevo en la industria.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">cada rango de frecuencia. Un ecualizador gr\u00e1fico controlado por DSP y 25 configuraciones ayudan a acondicionar su entorno ac\u00fastico al tiempo que ofrecen nuevos niveles de versatilidad en un monitor de estudio. Los controladores coincidentes (10&#8243;, 4.5&#8243;, 1&#8243;) fabricados con Kevlar\u00ae garantizan la misma integridad sonora<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">en todas las frecuencias, minimiza la fatiga auditiva y ofrece una experiencia auditiva incre\u00edblemente equilibrada.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Una nueva caja de altavoz dise\u00f1ada cient\u00edficamente y un puerto de disparo frontal ofrecen una extensi\u00f3n y precisi\u00f3n excepcionales de gama baja, impacto y posicionamiento flexible en la sala.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El nuevo amplificador de potencia Clase D personalizado, potente pero eficiente, impulsa los altavoces de manera uniforme y m\u00e1s eficiente a temperaturas de funcionamiento reducidas y mejora la integridad del audio.<\/span><\/span><\/p>\n<p>3PARKRRP103G4E<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":16918,"template":"","meta":[],"pwb-brand":[4350],"product_brand":[],"product_cat":[2405,114],"product_tag":[],"class_list":["post-16915","product","type-product","status-publish","has-post-thumbnail","pwb-brand-krk","product_cat-audio-pro","product_cat-monitores","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monitor Estudio KRK Rokit RP10-3 G4 (PAR) - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monitor Estudio KRK Rokit RP10-3 G4 (PAR) - Music Hall\" \/>\n<meta property=\"og:description\" content=\"El nuevo y estruendoso monitor profesional de tres amplificadores KRK ROKIT RP103 G4 (Generaci\u00f3n 4) de 10&quot; lleva la creatividad de la m\u00fasica y el sonido a un nivel completamente nuevo en la industria. cada rango de frecuencia. Un ecualizador gr\u00e1fico controlado por DSP y 25 configuraciones ayudan a acondicionar su entorno ac\u00fastico al tiempo que ofrecen nuevos niveles de versatilidad en un monitor de estudio. Los controladores coincidentes (10&quot;, 4.5&quot;, 1&quot;) fabricados con Kevlar\u00ae garantizan la misma integridad sonora en todas las frecuencias, minimiza la fatiga auditiva y ofrece una experiencia auditiva incre\u00edblemente equilibrada. Una nueva caja de altavoz dise\u00f1ada cient\u00edficamente y un puerto de disparo frontal ofrecen una extensi\u00f3n y precisi\u00f3n excepcionales de gama baja, impacto y posicionamiento flexible en la sala. El nuevo amplificador de potencia Clase D personalizado, potente pero eficiente, impulsa los altavoces de manera uniforme y m\u00e1s eficiente a temperaturas de funcionamiento reducidas y mejora la integridad del audio.  3PARKRRP103G4E  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T12:12:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/11\/3PARKRRP103G4E2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monitor Estudio KRK Rokit RP10-3 G4 (PAR) - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/","og_locale":"es_ES","og_type":"article","og_title":"Monitor Estudio KRK Rokit RP10-3 G4 (PAR) - Music Hall","og_description":"El nuevo y estruendoso monitor profesional de tres amplificadores KRK ROKIT RP103 G4 (Generaci\u00f3n 4) de 10\" lleva la creatividad de la m\u00fasica y el sonido a un nivel completamente nuevo en la industria. cada rango de frecuencia. Un ecualizador gr\u00e1fico controlado por DSP y 25 configuraciones ayudan a acondicionar su entorno ac\u00fastico al tiempo que ofrecen nuevos niveles de versatilidad en un monitor de estudio. Los controladores coincidentes (10\", 4.5\", 1\") fabricados con Kevlar\u00ae garantizan la misma integridad sonora en todas las frecuencias, minimiza la fatiga auditiva y ofrece una experiencia auditiva incre\u00edblemente equilibrada. Una nueva caja de altavoz dise\u00f1ada cient\u00edficamente y un puerto de disparo frontal ofrecen una extensi\u00f3n y precisi\u00f3n excepcionales de gama baja, impacto y posicionamiento flexible en la sala. El nuevo amplificador de potencia Clase D personalizado, potente pero eficiente, impulsa los altavoces de manera uniforme y m\u00e1s eficiente a temperaturas de funcionamiento reducidas y mejora la integridad del audio.  3PARKRRP103G4E  &nbsp;","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-05-04T12:12:22+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/11\/3PARKRRP103G4E2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/","name":"Monitor Estudio KRK Rokit RP10-3 G4 (PAR) - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/11\/3PARKRRP103G4E2.jpg","datePublished":"2022-11-23T14:32:30+00:00","dateModified":"2026-05-04T12:12:22+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/11\/3PARKRRP103G4E2.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/11\/3PARKRRP103G4E2.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/monitor-estudio-krk-rokit-rp10-3-g4-par\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Monitor Estudio KRK Rokit RP10-3 G4 (PAR)"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":4350,"name":"KRK","slug":"krk"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/16915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/16918"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=16915"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=16915"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=16915"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=16915"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=16915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}