{"id":21643,"date":"2024-01-30T10:34:22","date_gmt":"2024-01-30T13:34:22","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=21643"},"modified":"2026-05-04T09:14:29","modified_gmt":"2026-05-04T12:14:29","slug":"guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/","title":{"rendered":"Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst"},"content":{"rendered":"<h3 class=\"col-md-12\">CARACTER\u00cdSTICAS<\/h3>\n<div class=\"js-feature-bullets\">\n<ul>\n<li>Cuerpo delgado de madera de tilo Aerodyne con tapa tallada ribeteada<\/li>\n<li>M\u00e1stil de arce con diapas\u00f3n de arce o palisandro de 12\u201d de radio<\/li>\n<li>Pala pintada a juego<\/li>\n<li>Pastillas especiales Aerodyne<\/li>\n<li>Puente Babicz\u00ae FCH<\/li>\n<li>Clavijero de bloqueo<\/li>\n<\/ul>\n<p>CUERPO DELGADO DE TILO AERODYNE CON TAPA TALLADA RIBETEADA<br \/>\nEl tilo es una madera tonal premium c\u00e9lebre por su equilibrio de agudos claros, medios potentes y graves c\u00e1lidos. Los elegantes contornos &#8220;aerodin\u00e1micos&#8221; del cuerpo a\u00f1aden comodidad y estilo.<\/p>\n<p>M\u00c1STIL MODERNO EN FORMA DE &#8220;C&#8221; CON RADIO DE DIAPAS\u00d3N DE 12 &#8221;<br \/>\nEl perfil en &#8220;C&#8221; moderno se siente r\u00e1pido y suave, mientras que el radio de 12&#8243; permite hacer grandes bendings sin esfuerzo.<\/p>\n<p>CABEZAL PINTADO A JUEGO.<br \/>\nUn elegante cabezal pintado a juego complementa cada acabado \u00fanico.<\/p>\n<p>NUEVAS PASTILLAS ESPECIALES AERODYNE<br \/>\nLas nuevas pastillas Aerodyne Special est\u00e1n dise\u00f1adas para proporcionar a cada modelo un tono Fender completo y articulado.<\/p>\n<p>PUENTE BABICZ FCH<br \/>\nLos puentes Babicz Full-Contact Hardware ofrecen m\u00e1s contacto entre las cuerdas, las monturas y el cuerpo del instrumento para aumentar el sustain y la resonancia.<\/p>\n<p>CLAVIJERO DE BLOQUEO DELUXE<br \/>\nLos clavijeros Deluxe Locking aumentan la estabilidad de la afinaci\u00f3n y hacen que los cambios de cuerda sean r\u00e1pidos y f\u00e1ciles con un aspecto moderno.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La serie especial Aerodyne ofrece una versi\u00f3n contempor\u00e1nea de los dise\u00f1os cl\u00e1sicos de Fender\u00ae. Las l\u00edneas aerodin\u00e1micas distintivas, las pastillas personalizadas, el hardware de \u00faltima generaci\u00f3n, los acabados deslumbrantes y las siluetas inconfundibles se combinan para crear instrumentos que son puros, decididos y familiares al instante. y radicalmente nuevo.<\/p>\n<p>La Aerodyne Special Stratocaster\u00ae HSS presenta una nueva apariencia elegante con colores vibrantes que adornan el cuerpo de tilo elegantemente encuadernado y la pala a juego. Un m\u00e1stil moderno con acabado satinado en forma de &#8220;C&#8221; con diapas\u00f3n de radio de 12 &#8220;garantiza la comodidad, mientras que las pastillas Stratocaster vintage de nuevo dise\u00f1o acopladas a una pastilla de puente humbucking con sonido especial y un tr\u00e9molo Babicz\u00ae Z-Series FCH-2 Point brindan un equilibrio perfecto de alto rendimiento y tono Fender cl\u00e1sico.<\/p>\n<p>La Aerodyne Special Stratocaster\u00ae HSS fabricada en Jap\u00f3n inspira con un estilo futurista, detalles premium y un tono excepcional. Los dise\u00f1os audaces y originales que inspiraron a generaciones siguen vivos en la serie Aerodyne Special.<\/p>\n<p>0252102371E<\/p>\n","protected":false},"featured_media":21644,"template":"","meta":[],"pwb-brand":[85],"product_brand":[],"product_cat":[79,74,68],"product_tag":[5169],"class_list":["post-21643","product","type-product","status-publish","has-post-thumbnail","pwb-brand-fender","product_cat-guitarras","product_cat-guitarras-electricas","product_cat-instrumentos-musicales","product_tag-fender_0124","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst - Music Hall\" \/>\n<meta property=\"og:description\" content=\"La serie especial Aerodyne ofrece una versi\u00f3n contempor\u00e1nea de los dise\u00f1os cl\u00e1sicos de Fender\u00ae. Las l\u00edneas aerodin\u00e1micas distintivas, las pastillas personalizadas, el hardware de \u00faltima generaci\u00f3n, los acabados deslumbrantes y las siluetas inconfundibles se combinan para crear instrumentos que son puros, decididos y familiares al instante. y radicalmente nuevo.  La Aerodyne Special Stratocaster\u00ae HSS presenta una nueva apariencia elegante con colores vibrantes que adornan el cuerpo de tilo elegantemente encuadernado y la pala a juego. Un m\u00e1stil moderno con acabado satinado en forma de &quot;C&quot; con diapas\u00f3n de radio de 12 &quot;garantiza la comodidad, mientras que las pastillas Stratocaster vintage de nuevo dise\u00f1o acopladas a una pastilla de puente humbucking con sonido especial y un tr\u00e9molo Babicz\u00ae Z-Series FCH-2 Point brindan un equilibrio perfecto de alto rendimiento y tono Fender cl\u00e1sico.  La Aerodyne Special Stratocaster\u00ae HSS fabricada en Jap\u00f3n inspira con un estilo futurista, detalles premium y un tono excepcional. Los dise\u00f1os audaces y originales que inspiraron a generaciones siguen vivos en la serie Aerodyne Special.  0252102371E\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T12:14:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0252102371E.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/","og_locale":"es_ES","og_type":"article","og_title":"Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst - Music Hall","og_description":"La serie especial Aerodyne ofrece una versi\u00f3n contempor\u00e1nea de los dise\u00f1os cl\u00e1sicos de Fender\u00ae. Las l\u00edneas aerodin\u00e1micas distintivas, las pastillas personalizadas, el hardware de \u00faltima generaci\u00f3n, los acabados deslumbrantes y las siluetas inconfundibles se combinan para crear instrumentos que son puros, decididos y familiares al instante. y radicalmente nuevo.  La Aerodyne Special Stratocaster\u00ae HSS presenta una nueva apariencia elegante con colores vibrantes que adornan el cuerpo de tilo elegantemente encuadernado y la pala a juego. Un m\u00e1stil moderno con acabado satinado en forma de \"C\" con diapas\u00f3n de radio de 12 \"garantiza la comodidad, mientras que las pastillas Stratocaster vintage de nuevo dise\u00f1o acopladas a una pastilla de puente humbucking con sonido especial y un tr\u00e9molo Babicz\u00ae Z-Series FCH-2 Point brindan un equilibrio perfecto de alto rendimiento y tono Fender cl\u00e1sico.  La Aerodyne Special Stratocaster\u00ae HSS fabricada en Jap\u00f3n inspira con un estilo futurista, detalles premium y un tono excepcional. Los dise\u00f1os audaces y originales que inspiraron a generaciones siguen vivos en la serie Aerodyne Special.  0252102371E","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-05-04T12:14:29+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0252102371E.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/","name":"Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0252102371E.jpg","datePublished":"2024-01-30T13:34:22+00:00","dateModified":"2026-05-04T12:14:29+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0252102371E.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0252102371E.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-aerodyne-special-stratocaster-hss-hot-rod-burst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Guitarra El\u00e9ctrica Fender AERODYNE SPECIAL STRATOCASTER\u00ae HSS Hot Rod Burst"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":85,"name":"Fender","slug":"fender"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/21643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/21644"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=21643"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=21643"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=21643"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=21643"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=21643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}