{"id":21671,"date":"2024-01-30T14:03:39","date_gmt":"2024-01-30T17:03:39","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=21671"},"modified":"2026-05-04T09:14:29","modified_gmt":"2026-05-04T12:14:29","slug":"guitarra-electrica-fender-stevie-ray-vaughan-stratocaster","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/","title":{"rendered":"Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae"},"content":{"rendered":"<h3 class=\"col-md-12\">CARACTER\u00cdSTICAS<\/h3>\n<div class=\"js-feature-bullets\">\n<ul>\n<li>M\u00e1stil ovalado con perfil de principios de los a\u00f1os 60<\/li>\n<li>Diapas\u00f3n de madera brasile\u00f1a de pau ferro con trastes jumbo<\/li>\n<li>Pastillas Texas Special\u2122 Strat<\/li>\n<li>Golpeador negro con las iniciales SRV grabadas en blanco<\/li>\n<li>Herrajes dorados<\/li>\n<li>Puente de estilo vintage con palanca en la parte superior<\/li>\n<\/ul>\n<p>JUMBO FRETS<br \/>\nLos trastes jumbo ofrecen el perfil de mayor altura y grosor disponible, lo que permite un mejor control en la pulsaci\u00f3n y al mismo tiempo facilita el vibrato y los estiramientos de cuerdas. Una muy buena opci\u00f3n para los guitarristas con manos grandes y dedos gruesos.<\/p>\n<p>THICK OVAL NECK<br \/>\nComo el propio Vaughan prefer\u00eda, su Stratocaster Signature model monta un m\u00e1stil ovalado de perfil grueso, (silueta del corte transversal del m\u00e1stil), que aporta una distintiva sensaci\u00f3n de confort a la mano de digitaci\u00f3n. Su masa superior da lugar a un sonido y un sustain mejorados.<\/p>\n<p>TEXAS SPECIAL\u2122 PICKUPS<br \/>\nLas pastillas Texas Special de bobina simple presentan un nivel de bobinado extra ideal para el sonido del blues de Texas. Equipadas con polos magn\u00e9ticos de Alnico 5 y cable de bobinado recubierto en enamel, montan imanes escalonados para una mejor equilibrio de salida en cada cuerda. Las Texas Special pueden sonar cantarinas, hasta chillonas, y producir infinidad de sonidos desde unos graves potentes y unas frecuencias medias muy bien enfocadas hasta unos agudos cristalinos.<\/p>\n<p>\u201cSRV\u201d PICKGUARD<br \/>\nSeguramente el elemento visual m\u00e1s distintivo de esta Stratocaster es su golpeador negro con las iniciales de Vaughan grabadas en blanco.<\/p>\n<p>PAU FERRO FINGERBOARD<br \/>\nFant\u00e1stica madera para los diapasones, el pau ferro es una madera de procedencia suramericana con excelentes propiedades ac\u00fasticas. Con unas sensaciones y caracter\u00edsticas de sonido similares al palosanto, el pau ferro es una madera de color m\u00e1s claro y de mayor dureza.<\/p>\n<p>LEFT-HANDED STRATOCASTER TREMOLO<br \/>\nParece ser que Vaughan prefer\u00eda la disposici\u00f3n de los puentes de guitarra para zurdos, (es decir, instalados en posici\u00f3n invertida), ya que la palanca en la parte superior ofrec\u00eda mayor parecido a la disposici\u00f3n utilizada por Jimi Hendrix, quien al emplear instrumentos dise\u00f1ados para diestros, y darles la vuelta, tocaba con la palanca ubicada en la parte superior del puente.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"row long-description\">\n<div class=\"js-long-description-heading\">\n<h2>PURO SONIDO Y ESTILO STEVIE RAY VAUGHAN<\/h2>\n<\/div>\n<div class=\"js-long-description\">Si hubiera un Monte Rushmore de la Stratocaster, Stevie Ray Vaughan estar\u00eda esculpido all\u00ed. La Fender Stevie Ray Vaughan Stratocaster es una nueva versi\u00f3n de la guitarra favorita de Vaughan, su famosa Strat &#8220;Number One&#8221; con la que asombr\u00f3 a audiencias de todo el mundo con su inimitable estilo de blues tejano. Si buscas el sonido y estilo puros de Stevie Ray Vaughan, esta Stratocaster es el homenaje de Fender para uno de los m\u00e1s venerados maestros de la guitarra blues.<br \/>\n0109200800E<\/div>\n<\/div>\n","protected":false},"featured_media":21672,"template":"","meta":[],"pwb-brand":[85],"product_brand":[],"product_cat":[74,5213],"product_tag":[],"class_list":["post-21671","product","type-product","status-publish","has-post-thumbnail","pwb-brand-fender","product_cat-guitarras-electricas","product_cat-signature","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae - Music Hall\" \/>\n<meta property=\"og:description\" content=\"PURO SONIDO Y ESTILO STEVIE RAY VAUGHAN  Si hubiera un Monte Rushmore de la Stratocaster, Stevie Ray Vaughan estar\u00eda esculpido all\u00ed. La Fender Stevie Ray Vaughan Stratocaster es una nueva versi\u00f3n de la guitarra favorita de Vaughan, su famosa Strat &quot;Number One&quot; con la que asombr\u00f3 a audiencias de todo el mundo con su inimitable estilo de blues tejano. Si buscas el sonido y estilo puros de Stevie Ray Vaughan, esta Stratocaster es el homenaje de Fender para uno de los m\u00e1s venerados maestros de la guitarra blues. 0109200800E\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T12:14:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0109200800E.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/","og_locale":"es_ES","og_type":"article","og_title":"Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae - Music Hall","og_description":"PURO SONIDO Y ESTILO STEVIE RAY VAUGHAN  Si hubiera un Monte Rushmore de la Stratocaster, Stevie Ray Vaughan estar\u00eda esculpido all\u00ed. La Fender Stevie Ray Vaughan Stratocaster es una nueva versi\u00f3n de la guitarra favorita de Vaughan, su famosa Strat \"Number One\" con la que asombr\u00f3 a audiencias de todo el mundo con su inimitable estilo de blues tejano. Si buscas el sonido y estilo puros de Stevie Ray Vaughan, esta Stratocaster es el homenaje de Fender para uno de los m\u00e1s venerados maestros de la guitarra blues. 0109200800E","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-05-04T12:14:29+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0109200800E.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/","name":"Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0109200800E.jpg","datePublished":"2024-01-30T17:03:39+00:00","dateModified":"2026-05-04T12:14:29+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0109200800E.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/01\/0109200800E.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-stevie-ray-vaughan-stratocaster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Guitarra El\u00e9ctrica Fender STEVIE RAY VAUGHAN STRATOCASTER\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":85,"name":"Fender","slug":"fender"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/21671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/21672"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=21671"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=21671"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=21671"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=21671"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=21671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}