{"id":22308,"date":"2024-03-04T17:51:19","date_gmt":"2024-03-04T20:51:19","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=22308"},"modified":"2026-05-04T09:14:49","modified_gmt":"2026-05-04T12:14:49","slug":"guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/","title":{"rendered":"Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire"},"content":{"rendered":"<div><strong>True Jet Essence con Broad&#8217;Tron\u2122 Might<\/strong><\/div>\n<div>El nuevo G5220 Electromatic Jet BT Single-Cut con V-Stoptail ofrece potencia Broad&#8217;Tron\u2122 con la cl\u00e1sica claridad Jet.<\/div>\n<div><strong>Cuerpos<\/strong><\/div>\n<div>de caoba con c\u00e1mara En el coraz\u00f3n de cada Electromatic Jet BT hay un cuerpo de caoba con c\u00e1mara y tapa de arce que produce un rango medio rico y presente que acent\u00faa los grandes graves y los agudos resplandecientes.<\/div>\n<div><strong>Pastillas Black Top Broad&#8217;Tron totalmente nuevas<\/strong><\/div>\n<div>Un par de pastillas Black Top Broad&#8217;Tron impulsan el cuerpo de caoba con c\u00e1mara con tapa de arce a trav\u00e9s de una sobremarcha gruesa y agresiva mientras mantienen una definici\u00f3n asombrosa y un equilibrio de notas adecuado para el tono limpio m\u00e1s pr\u00edstino.<\/div>\n<div><strong>Controles vers\u00e1tiles<\/strong><\/div>\n<div>El Electromatic Jet BT est\u00e1 equipado con caracter\u00edsticas esenciales que le brindan un control tonal completo.\u00a0La combinaci\u00f3n de controles de volumen de captaci\u00f3n individuales, tono maestro y volumen maestro con circuito de purga de agudos proporciona un control global intuitivo sobre la configuraci\u00f3n de la captaci\u00f3n y el tono.<\/div>\n<ul>\n<li>Cuerpo de caoba con c\u00e1mara mejorada con tapa de arce para un perfil sonoro fuerte y un equilibrio ac\u00fastico excepcional<\/li>\n<li>M\u00e1stil de caoba de ajuste inferior para acceso y rendimiento sin esfuerzo<\/li>\n<li>Diapas\u00f3n de laurel de 12\u201d de radio con 22 trastes medium jumbo<\/li>\n<li>Pastillas dobles Black Top Broad&#8217;Tron\u2122<\/li>\n<li>Volumen maestro con circuito de purga de agudos, tono maestro y controles de volumen de captaci\u00f3n individuales<\/li>\n<li>Cordal Gretsch V-Stoptail<\/li>\n<li>Puente anclado Adjusto-Matic\u2122<\/li>\n<li>Las citas mejoradas incluyen clavijero encuadernado, tapa de clavijero de cara sencilla, fileteado de inspiraci\u00f3n vintage, incrustaciones de Big Block y llaves de afinaci\u00f3n cerradas<\/li>\n<li>herrajes cromados<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sofisticados y sensibles, los modelos Electromatic\u00ae Jet\u2122 BT son los perfectos instrumentos reales, puros y potentes de Gretsch\u00ae. Son tu Gretsch del siguiente paso: audaces, din\u00e1micos y articulados, y fabricados con el sonido, el estilo y la jugabilidad esenciales de Gretsch.<\/p>\n<p>2517110533E<\/p>\n","protected":false},"featured_media":22310,"template":"","meta":[],"pwb-brand":[908],"product_brand":[],"product_cat":[79,74,68],"product_tag":[5254],"class_list":["post-22308","product","type-product","status-publish","has-post-thumbnail","pwb-brand-gretsch","product_cat-guitarras","product_cat-guitarras-electricas","product_cat-instrumentos-musicales","product_tag-5254","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Sofisticados y sensibles, los modelos Electromatic\u00ae Jet\u2122 BT son los perfectos instrumentos reales, puros y potentes de Gretsch\u00ae. Son tu Gretsch del siguiente paso: audaces, din\u00e1micos y articulados, y fabricados con el sonido, el estilo y la jugabilidad esenciales de Gretsch.  2517110533E\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T12:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/03\/2517110533E-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/","og_locale":"es_ES","og_type":"article","og_title":"Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire - Music Hall","og_description":"Sofisticados y sensibles, los modelos Electromatic\u00ae Jet\u2122 BT son los perfectos instrumentos reales, puros y potentes de Gretsch\u00ae. Son tu Gretsch del siguiente paso: audaces, din\u00e1micos y articulados, y fabricados con el sonido, el estilo y la jugabilidad esenciales de Gretsch.  2517110533E","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-05-04T12:14:49+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/03\/2517110533E-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/","name":"Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/03\/2517110533E-jpg.webp","datePublished":"2024-03-04T20:51:19+00:00","dateModified":"2026-05-04T12:14:49+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/03\/2517110533E-jpg.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/03\/2517110533E-jpg.webp","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-gretsch-g5220-electromatic-jet-bt-sgle-cut-with-v-stoptail-midnight-sapphire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Guitarra el\u00e9ctrica Gretsch G5220 Electromatic Jet Bt Sgle-Cut With V-Stoptail, Midnight Sapphire"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":908,"name":"Gretsch Guitars","slug":"gretsch"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/22308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/22310"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=22308"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=22308"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=22308"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=22308"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=22308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}