{"id":24501,"date":"2024-06-20T15:36:03","date_gmt":"2024-06-20T19:36:03","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=24501"},"modified":"2026-07-08T09:42:24","modified_gmt":"2026-07-08T12:42:24","slug":"laney-irf-dualrig212","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/","title":{"rendered":"Laney IRF-Dualrig212"},"content":{"rendered":"<p>DETALLES<br \/>\n2 canales<\/p>\n<p>60 vatios RMS<\/p>\n<p>Salida XLR D.I. &#8211; balanceada<\/p>\n<p>Cargado con 2 controladores de 12 HH<\/p>\n<p>Los bucles FX son importantes, ya que permiten a\u00f1adir efectos a la ruta de la se\u00f1al en un lugar espec\u00edfico entre el preamplificador y la secci\u00f3n de salida de un amplificador. Aqu\u00ed es donde los bucles de efectos son importantes, ya que te permiten poner efectos basados en el tiempo despu\u00e9s de la secci\u00f3n de preamplificador distorsionada. Por ejemplo, la distorsi\u00f3n retardada suena diferente al retardo distorsionado, pru\u00e9balo.<\/p>\n<p>Agarraderas ergon\u00f3micas<\/p>\n<p>La emulaci\u00f3n de gabinete conmutable le permite agregar las caracter\u00edsticas de frecuencia de un gabinete de su elecci\u00f3n a su se\u00f1al DI sin la necesidad de microfonear un gabinete.<\/p>\n<p>Impulso conmutable con el pie<\/p>\n<p>Retrato u paisaje<\/p>\n<p>Toma de auriculares<\/p>\n<p>CARACTER\u00cdSTICAS PRINCIPALES<br \/>\n60 vatios RMS<br \/>\nDos canales con ganancia y volumen<br \/>\nSalida DI basada en IR con emulaci\u00f3n activada\/desactivada<br \/>\nReverberaci\u00f3n Springline &#8211; Algoritmo SECRETPATH<br \/>\nCH1 con modos de ganancia ASYM\/CLEAN\/SYM seleccionables<br \/>\nCH2 con voz brillante, plana y oscura seleccionable<br \/>\nPila de tonos pasivos de 3 bandas<br \/>\nNivel de entrada de pre-boost y pedal con indicador LED.<br \/>\nSalida de altavoz<br \/>\nModos de alta y baja potencia (baja potencia &lt;1W)<br \/>\nBucle de efectos de alta calidad aislado del transformador<br \/>\nConector de entrada auxiliar est\u00e9reo de 3,5 mm<br \/>\nSalida de auriculares<br \/>\nFuente de alimentaci\u00f3n de voltaje universal de 100-240 V incluida (24 V)<br \/>\nGS212FE &#8211; 120 W RMS, 240 W continuo, 480 W pico<br \/>\n2&#215;12&#8243; HH Controladores de alto rendimiento dise\u00f1ados &#8211; H1260<br \/>\nImpedancia de 8 ohmios<br \/>\nConstrucci\u00f3n robusta de madera.<br \/>\nEsquinas de metal negro<br \/>\nOrientaci\u00f3n vertical<br \/>\nZ\u00f3calo Jack de 6,3 mm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La serie IRONHEART FOUNDRY ha tomado la potencia y el dinamismo de nuestros amplificadores de v\u00e1lvulas IRONHEART y ha fundido y forjado sus caracter\u00edsticas para ofrecer una potencia monstruosa y una versatilidad incre\u00edble en una forma ultracompacta. El IRF-DUALRIG212 consiste en el incre\u00edble IRF-DUALTOP empaquetado con un gabinete GS212FE dise\u00f1ado a medida. Creado para ofrecer todo el tono y la flexibilidad del IRF-DUALTOP. Cargado con un par de controladores HH 1260 dise\u00f1ados a medida que entregan 60 vatios RMS @ 8 ohmios. Toda la madera, la construcci\u00f3n de la parte trasera abierta, las esquinas de metal negro y un conector de 6,3 mm le dan un sonido y una sensaci\u00f3n profesionales. No te decepcionar\u00e1.<\/p>\n","protected":false},"featured_media":24504,"template":"","meta":[],"pwb-brand":[87],"product_brand":[],"product_cat":[116,115],"product_tag":[],"class_list":["post-24501","product","type-product","status-publish","has-post-thumbnail","pwb-brand-laney","product_cat-amp-guitarras","product_cat-amplificadores","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laney IRF-Dualrig212 - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laney IRF-Dualrig212 - Music Hall\" \/>\n<meta property=\"og:description\" content=\"La serie IRONHEART FOUNDRY ha tomado la potencia y el dinamismo de nuestros amplificadores de v\u00e1lvulas IRONHEART y ha fundido y forjado sus caracter\u00edsticas para ofrecer una potencia monstruosa y una versatilidad incre\u00edble en una forma ultracompacta. El IRF-DUALRIG212 consiste en el incre\u00edble IRF-DUALTOP empaquetado con un gabinete GS212FE dise\u00f1ado a medida. Creado para ofrecer todo el tono y la flexibilidad del IRF-DUALTOP. Cargado con un par de controladores HH 1260 dise\u00f1ados a medida que entregan 60 vatios RMS @ 8 ohmios. Toda la madera, la construcci\u00f3n de la parte trasera abierta, las esquinas de metal negro y un conector de 6,3 mm le dan un sonido y una sensaci\u00f3n profesionales. No te decepcionar\u00e1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:42:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/06\/IRF-DUALRIG212E-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laney IRF-Dualrig212 - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/","og_locale":"es_ES","og_type":"article","og_title":"Laney IRF-Dualrig212 - Music Hall","og_description":"La serie IRONHEART FOUNDRY ha tomado la potencia y el dinamismo de nuestros amplificadores de v\u00e1lvulas IRONHEART y ha fundido y forjado sus caracter\u00edsticas para ofrecer una potencia monstruosa y una versatilidad incre\u00edble en una forma ultracompacta. El IRF-DUALRIG212 consiste en el incre\u00edble IRF-DUALTOP empaquetado con un gabinete GS212FE dise\u00f1ado a medida. Creado para ofrecer todo el tono y la flexibilidad del IRF-DUALTOP. Cargado con un par de controladores HH 1260 dise\u00f1ados a medida que entregan 60 vatios RMS @ 8 ohmios. Toda la madera, la construcci\u00f3n de la parte trasera abierta, las esquinas de metal negro y un conector de 6,3 mm le dan un sonido y una sensaci\u00f3n profesionales. No te decepcionar\u00e1.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:42:24+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/06\/IRF-DUALRIG212E-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/","name":"Laney IRF-Dualrig212 - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/06\/IRF-DUALRIG212E-jpg.webp","datePublished":"2024-06-20T19:36:03+00:00","dateModified":"2026-07-08T12:42:24+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/06\/IRF-DUALRIG212E-jpg.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/06\/IRF-DUALRIG212E-jpg.webp","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-irf-dualrig212\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Laney IRF-Dualrig212"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":87,"name":"Laney Amplification","slug":"laney"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/24501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/24504"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=24501"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=24501"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=24501"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=24501"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=24501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}