{"id":25669,"date":"2024-08-29T10:07:34","date_gmt":"2024-08-29T14:07:34","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=25669"},"modified":"2026-05-04T09:15:43","modified_gmt":"2026-05-04T12:15:43","slug":"guitarra-electrica-fender-lincoln-brewster-stratocaster","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/","title":{"rendered":"Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae"},"content":{"rendered":"<h3>Caracter\u00edsticas<\/h3>\n<div class=\"js-feature-bullets\">\n<ul>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">Cuerpo de fresno con acabado lacado.<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">M\u00e1stil en forma de &#8220;V suave&#8221;; Diapas\u00f3n de radio compuesto de 9.5 &#8220;-14&#8221;; 22 trastes medium jumbo.<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">Una pastilla del puente Strat de bobina simple \u00c1rea 61 de DiMarzio; dos pastillas DiMarzio Area 58 de bobina simple Strat en el centro y m\u00e1stil.<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">Preamplificador activo con control de medios.<\/span><\/li>\n<\/ul>\n<p><strong>CUERPO DE FRESNO<\/strong><\/p>\n<p>Una madera tonal t\u00edpica de Fender de la d\u00e9cada de los 50, el fresno tiene una gran articulaci\u00f3n y presencia con un excelente equilibrio entre brillo y graves.<\/p>\n<\/div>\n<p><strong>PASTILLAS AREA DE <\/strong><strong>DIMARZIO<\/strong><\/p>\n<p>EI set de pastillas Area 58 y Area 61 ofrece tonos vintage de bobina simple, sin el zumbido del estilo vintage.<\/p>\n<p><strong>DIAPAS\u00d3N DE RADIO COMPUESTO<\/strong><\/p>\n<p>EI radio de 9.5 &#8220;a 14&#8221; es muy c\u00f3modo, 10 que permite velocidad y flexibilidad sin obstrucciones.<\/p>\n<p><strong>SISTEMA INNOVADOR TREMOLO<\/strong><\/p>\n<p>Este dise\u00f1o de 2 puntos presenta sillines de acero doblado para un tono cl\u00e1sico y una palanca de tr\u00e9molo pop-in para mayor comodidad.<\/p>\n<p><strong>PREVIO BOOST A BORDO<\/strong><\/p>\n<p>Se accede f\u00e1cilmente a trav\u00e9s de un posh \/ pull en el volumen maestro, con el nivel de salida controlado con la perilla Tone I.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conmovedor y din\u00e1mico, el estilo de Lincoln Brewster ha inspirado y motivado a innumerables fan\u00e1ticos en el transcurso de sus 25 a\u00f1os de carrera. Con un cuerpo de fresno y un sorprendente acabado de laca Aztec Gold, la Lincoln Brewster Stratocaster es un verdadero cl\u00e1sico actual, que combina contornos de cuerpo atemporales y una forma de m\u00e1stil vintage con caracter\u00edsticas actualizadas como un diapas\u00f3n de radio compuesto, tr\u00e9molo de 2 puntos con sillines de acero curvado y palanca \u201cpop in\u201d. Un tr\u00edo de pastillas de bobina simple: dos pastillas DiMarzio\u00ae Area 58 \u2122 en las posiciones del m\u00e1stil y centro, y una DiMarzio Area 61 \u2122 en el puente, ofrecen tonos vintage sin zumbidos. El m\u00e1stil de arce &#8220;Soft V&#8221; con acabado de laca de nitrocelulosa y los 22 trastes m\u00e9dium jumbo del diapas\u00f3n de arce est\u00e1n dise\u00f1ados para brindar velocidad y comodidad. Un boost activo a bordo, activado a trav\u00e9s de un control de volumen push \/ pull, y un refuerzo de medios controlado por la perilla Tone 1, le dan a esta guitarra potencia extra y enfoque para cualquier situaci\u00f3n musical. Esta guitarra rica en caracter\u00edsticas tambi\u00e9n tiene toques est\u00e9ticos cl\u00e1sicos como herrajes cromados, perillas de pl\u00e1stico blanco envejecido, un golpeador Eggshell de 1 capa y clavijero de bloqueo de estilo vintage.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/M3UcbalNKE0?si=63ngyZcrrYPPEZmj\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"featured_media":25673,"template":"","meta":[],"pwb-brand":[85],"product_brand":[],"product_cat":[74,5213],"product_tag":[5218],"class_list":["post-25669","product","type-product","status-publish","has-post-thumbnail","pwb-brand-fender","product_cat-guitarras-electricas","product_cat-signature","product_tag-fw24","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Conmovedor y din\u00e1mico, el estilo de Lincoln Brewster ha inspirado y motivado a innumerables fan\u00e1ticos en el transcurso de sus 25 a\u00f1os de carrera. Con un cuerpo de fresno y un sorprendente acabado de laca Aztec Gold, la Lincoln Brewster Stratocaster es un verdadero cl\u00e1sico actual, que combina contornos de cuerpo atemporales y una forma de m\u00e1stil vintage con caracter\u00edsticas actualizadas como un diapas\u00f3n de radio compuesto, tr\u00e9molo de 2 puntos con sillines de acero curvado y palanca \u201cpop in\u201d. Un tr\u00edo de pastillas de bobina simple: dos pastillas DiMarzio\u00ae Area 58 \u2122 en las posiciones del m\u00e1stil y centro, y una DiMarzio Area 61 \u2122 en el puente, ofrecen tonos vintage sin zumbidos. El m\u00e1stil de arce &quot;Soft V&quot; con acabado de laca de nitrocelulosa y los 22 trastes m\u00e9dium jumbo del diapas\u00f3n de arce est\u00e1n dise\u00f1ados para brindar velocidad y comodidad. Un boost activo a bordo, activado a trav\u00e9s de un control de volumen push \/ pull, y un refuerzo de medios controlado por la perilla Tone 1, le dan a esta guitarra potencia extra y enfoque para cualquier situaci\u00f3n musical. Esta guitarra rica en caracter\u00edsticas tambi\u00e9n tiene toques est\u00e9ticos cl\u00e1sicos como herrajes cromados, perillas de pl\u00e1stico blanco envejecido, un golpeador Eggshell de 1 capa y clavijero de bloqueo de estilo vintage.  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T12:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/08\/0116502778E-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/","og_locale":"es_ES","og_type":"article","og_title":"Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae - Music Hall","og_description":"Conmovedor y din\u00e1mico, el estilo de Lincoln Brewster ha inspirado y motivado a innumerables fan\u00e1ticos en el transcurso de sus 25 a\u00f1os de carrera. Con un cuerpo de fresno y un sorprendente acabado de laca Aztec Gold, la Lincoln Brewster Stratocaster es un verdadero cl\u00e1sico actual, que combina contornos de cuerpo atemporales y una forma de m\u00e1stil vintage con caracter\u00edsticas actualizadas como un diapas\u00f3n de radio compuesto, tr\u00e9molo de 2 puntos con sillines de acero curvado y palanca \u201cpop in\u201d. Un tr\u00edo de pastillas de bobina simple: dos pastillas DiMarzio\u00ae Area 58 \u2122 en las posiciones del m\u00e1stil y centro, y una DiMarzio Area 61 \u2122 en el puente, ofrecen tonos vintage sin zumbidos. El m\u00e1stil de arce \"Soft V\" con acabado de laca de nitrocelulosa y los 22 trastes m\u00e9dium jumbo del diapas\u00f3n de arce est\u00e1n dise\u00f1ados para brindar velocidad y comodidad. Un boost activo a bordo, activado a trav\u00e9s de un control de volumen push \/ pull, y un refuerzo de medios controlado por la perilla Tone 1, le dan a esta guitarra potencia extra y enfoque para cualquier situaci\u00f3n musical. Esta guitarra rica en caracter\u00edsticas tambi\u00e9n tiene toques est\u00e9ticos cl\u00e1sicos como herrajes cromados, perillas de pl\u00e1stico blanco envejecido, un golpeador Eggshell de 1 capa y clavijero de bloqueo de estilo vintage.  &nbsp;","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-05-04T12:15:43+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/08\/0116502778E-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/","name":"Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/08\/0116502778E-jpg.webp","datePublished":"2024-08-29T14:07:34+00:00","dateModified":"2026-05-04T12:15:43+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/08\/0116502778E-jpg.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/08\/0116502778E-jpg.webp","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-fender-lincoln-brewster-stratocaster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Guitarra el\u00e9ctrica Fender Lincoln Brewster Stratocaster\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":85,"name":"Fender","slug":"fender"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/25669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/25673"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=25669"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=25669"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=25669"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=25669"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=25669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}