{"id":26234,"date":"2024-09-27T12:01:15","date_gmt":"2024-09-27T16:01:15","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=26234"},"modified":"2026-07-08T09:42:36","modified_gmt":"2026-07-08T12:42:36","slug":"daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/","title":{"rendered":"DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5"},"content":{"rendered":"<h2>Caracter\u00edsticas Principales de las Ca\u00f1as D&#8217;Addario VENN para Saxo Alto, G2, fuerza 2.5<\/h2>\n<ul>\n<li>Ca\u00f1a para Saxo Alto<\/li>\n<li>Fuerza 2.5<\/li>\n<li>Estratificaci\u00f3n \u00fanica de fibras de pol\u00edmero<\/li>\n<li>Combinaci\u00f3n de resinas y part\u00edculas de ca\u00f1as naturales<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D&#8217;Addario VENN: una ca\u00f1a sint\u00e9tica avanzada fabricada con fibras de pol\u00edmero, resina y elementos de ca\u00f1a natural. Dise\u00f1ada para ofrecer a los m\u00fasicos los beneficios de las ca\u00f1as sint\u00e9ticas sin comprometer el sonido y la funcionalidad de las ca\u00f1as naturales.<\/p>\n<p>Desarrollada por los ingenieros m\u00e1s venerados de la industria, la VENN se\u00f1ala una nueva era en la innovaci\u00f3n de los instrumentos de viento: la combinaci\u00f3n de la estabilidad y la longevidad de una ca\u00f1a sint\u00e9tica con el sonido y el tacto de la ca\u00f1a natural. Para imitar la estructura org\u00e1nica de la ca\u00f1a, han realizado ingenier\u00eda inversa de la propia ca\u00f1a, poniendo capas de diferentes fibras polim\u00e9ricas con resina y elementos naturales de ca\u00f1a para formar la ca\u00f1a en bruto.<\/p>\n","protected":false},"featured_media":26235,"template":"","meta":[],"pwb-brand":[94],"product_brand":[],"product_cat":[803],"product_tag":[3325,3198,804],"class_list":["post-26234","product","type-product","status-publish","has-post-thumbnail","pwb-brand-daddario","product_cat-pajuela","product_tag-cana","product_tag-lengueta","product_tag-pajuela","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5 - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5 - Music Hall\" \/>\n<meta property=\"og:description\" content=\"D&#039;Addario VENN: una ca\u00f1a sint\u00e9tica avanzada fabricada con fibras de pol\u00edmero, resina y elementos de ca\u00f1a natural. Dise\u00f1ada para ofrecer a los m\u00fasicos los beneficios de las ca\u00f1as sint\u00e9ticas sin comprometer el sonido y la funcionalidad de las ca\u00f1as naturales.  Desarrollada por los ingenieros m\u00e1s venerados de la industria, la VENN se\u00f1ala una nueva era en la innovaci\u00f3n de los instrumentos de viento: la combinaci\u00f3n de la estabilidad y la longevidad de una ca\u00f1a sint\u00e9tica con el sonido y el tacto de la ca\u00f1a natural. Para imitar la estructura org\u00e1nica de la ca\u00f1a, han realizado ingenier\u00eda inversa de la propia ca\u00f1a, poniendo capas de diferentes fibras polim\u00e9ricas con resina y elementos naturales de ca\u00f1a para formar la ca\u00f1a en bruto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/09\/679182_7883-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5 - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/","og_locale":"es_ES","og_type":"article","og_title":"DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5 - Music Hall","og_description":"D'Addario VENN: una ca\u00f1a sint\u00e9tica avanzada fabricada con fibras de pol\u00edmero, resina y elementos de ca\u00f1a natural. Dise\u00f1ada para ofrecer a los m\u00fasicos los beneficios de las ca\u00f1as sint\u00e9ticas sin comprometer el sonido y la funcionalidad de las ca\u00f1as naturales.  Desarrollada por los ingenieros m\u00e1s venerados de la industria, la VENN se\u00f1ala una nueva era en la innovaci\u00f3n de los instrumentos de viento: la combinaci\u00f3n de la estabilidad y la longevidad de una ca\u00f1a sint\u00e9tica con el sonido y el tacto de la ca\u00f1a natural. Para imitar la estructura org\u00e1nica de la ca\u00f1a, han realizado ingenier\u00eda inversa de la propia ca\u00f1a, poniendo capas de diferentes fibras polim\u00e9ricas con resina y elementos naturales de ca\u00f1a para formar la ca\u00f1a en bruto.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:42:36+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/09\/679182_7883-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/","name":"DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5 - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/09\/679182_7883-jpg.webp","datePublished":"2024-09-27T16:01:15+00:00","dateModified":"2026-07-08T12:42:36+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/09\/679182_7883-jpg.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/09\/679182_7883-jpg.webp","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/daddario-woodwinds-vas0125g2-venn-para-saxo-alto-2-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"DADDARIO WOODWINDS VAS0125G2 VENN para Saxo Alto 2.5"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":94,"name":"D'Addario","slug":"daddario"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/26234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/26235"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=26234"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=26234"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=26234"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=26234"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=26234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}