{"id":27058,"date":"2024-11-05T16:02:40","date_gmt":"2024-11-05T19:02:40","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=27058"},"modified":"2026-07-08T09:42:45","modified_gmt":"2026-07-08T12:42:45","slug":"hohner-armonica-big-river-harp-en-re-mayor-m590036x","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/","title":{"rendered":"Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X"},"content":{"rendered":"<div class=\"mb-40\">\n<div class=\"thumb-element row clearfix\">\n<div class=\"col-md-8 scroll-carousel-slider-col my-col\">\n<h4 class=\"light-head\">CARACTER\u00cdSTICAS<\/h4>\n<div class=\"bx-wrapper\">\n<div class=\"bx-viewport\" aria-live=\"polite\">\n<ul id=\"product-slider\" class=\"bxslider\">\n<li aria-hidden=\"false\">\n<div class=\"feature-content-box\">\n<h4 class=\"light-head\">Estructura modular<\/h4>\n<p>Las placas del peine, l\u00e1minas y cubiertas son intercambiables con todas las dem\u00e1s series de MS, con muchas combinaciones posibles para cualquier estilo de ejecuci\u00f3n.<\/p>\n<\/div>\n<\/li>\n<li aria-hidden=\"true\">\n<div class=\"feature-content-box\">\n<h4 class=\"light-head\">Cubiertas curvas<\/h4>\n<p>Las cubiertas garantizan un buen manejo.<\/p>\n<p><strong>Peine de pl\u00e1stico duradero<\/strong><\/p>\n<\/div>\n<\/li>\n<li aria-hidden=\"true\">\n<div class=\"feature-content-box\">\n<p>S\u00f3lido rendimiento en todas las condiciones clim\u00e1ticas gracias a un peine de pl\u00e1stico muy resistente.<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"accordion\" role=\"tablist\" aria-multiselectable=\"true\">\n<div class=\"card\">\n<div id=\"headingOne\" class=\"card-header\" role=\"tab\">\n<h5 class=\"mb-0\">ESPECIFICACIONES<\/h5>\n<\/div>\n<div id=\"collapseOne\" class=\"collapse show\" role=\"tabpanel\" aria-labelledby=\"headingOne\">\n<div class=\"card-block\">\n<table class=\"table table-sm\">\n<tbody>\n<tr>\n<td>Placa de leng\u00fcetas (material, espesor):<\/td>\n<td>Lat\u00f3n, 0,9 mm<\/td>\n<\/tr>\n<tr>\n<td>Placa de leng\u00fcetas (superficie):<\/td>\n<td>Lat\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>Leng\u00fcetas (n\u00famero material):<\/td>\n<td>20, Lat\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>Peine (material, color):<\/td>\n<td>ABS, negro<\/td>\n<\/tr>\n<tr>\n<td>Peine (superficie):<\/td>\n<td>ABS<\/td>\n<\/tr>\n<tr>\n<td>Boquilla (superficie):<\/td>\n<td>ABS<\/td>\n<\/tr>\n<tr>\n<td>Cubiertas:<\/td>\n<td>acero inoxidable<\/td>\n<\/tr>\n<tr>\n<td>Teclas:<\/td>\n<td>F#, F, E, Eb, D, Db, C, B(H), Bb, A, Ab, G<\/td>\n<\/tr>\n<tr>\n<td>Afinaci\u00f3n:<\/td>\n<td>Richter<\/td>\n<\/tr>\n<tr>\n<td>N\u00famero de orificios:<\/td>\n<td>10<\/td>\n<\/tr>\n<tr>\n<td>Tesitura:<\/td>\n<td>3 Octavas<\/td>\n<\/tr>\n<tr>\n<td>Longitud:<\/td>\n<td>10,5 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<h4 class=\"productName\">LA ARM\u00d3NICA PARA EL VIRTUOSO<\/h4>\n<p>Imagine sentarse en un vapor de ruedas, que flota suavemente por el Misisipi. El sol brilla, y usted solo mira mientras escucha m\u00fasica. La Big River Harp captura perfectamente este esp\u00edritu del delta del Misisipi, la libertad, la tranquilidad, desde el nombre. Es el punto de inicio perfecto para sus primeras expediciones al mundo del oeste, el folclore o el estilo country de Nashville.<\/p>\n<div class=\"mb-40\">\n<div class=\"thumb-element row clearfix\">\n<div class=\"col-md-8 scroll-carousel-slider-col my-col\"><\/div>\n<\/div>\n<\/div>\n<div id=\"accordion\" role=\"tablist\" aria-multiselectable=\"true\">\n<div class=\"card\">\n<div id=\"collapseOne\" class=\"collapse show\" role=\"tabpanel\" aria-labelledby=\"headingOne\">\n<div class=\"card-block\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":27057,"template":"","meta":[],"pwb-brand":[89],"product_brand":[],"product_cat":[415,68,69],"product_tag":[],"class_list":["post-27058","product","type-product","status-publish","has-post-thumbnail","pwb-brand-hohner","product_cat-armonicas","product_cat-instrumentos-musicales","product_cat-instrumentos-de-viento","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X - Music Hall\" \/>\n<meta property=\"og:description\" content=\"LA ARM\u00d3NICA PARA EL VIRTUOSO Imagine sentarse en un vapor de ruedas, que flota suavemente por el Misisipi. El sol brilla, y usted solo mira mientras escucha m\u00fasica. La Big River Harp captura perfectamente este esp\u00edritu del delta del Misisipi, la libertad, la tranquilidad, desde el nombre. Es el punto de inicio perfecto para sus primeras expediciones al mundo del oeste, el folclore o el estilo country de Nashville.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/11\/M590016X-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/","og_locale":"es_ES","og_type":"article","og_title":"Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X - Music Hall","og_description":"LA ARM\u00d3NICA PARA EL VIRTUOSO Imagine sentarse en un vapor de ruedas, que flota suavemente por el Misisipi. El sol brilla, y usted solo mira mientras escucha m\u00fasica. La Big River Harp captura perfectamente este esp\u00edritu del delta del Misisipi, la libertad, la tranquilidad, desde el nombre. Es el punto de inicio perfecto para sus primeras expediciones al mundo del oeste, el folclore o el estilo country de Nashville.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:42:45+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/11\/M590016X-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/","name":"Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/11\/M590016X-jpg.webp","datePublished":"2024-11-05T19:02:40+00:00","dateModified":"2026-07-08T12:42:45+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/11\/M590016X-jpg.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2024\/11\/M590016X-jpg.webp","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/hohner-armonica-big-river-harp-en-re-mayor-m590036x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Hohner Arm\u00f3nica Big River Harp en Re mayor M590036X"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":89,"name":"Hohner","slug":"hohner"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/27058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/27057"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=27058"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=27058"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=27058"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=27058"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=27058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}