{"id":29022,"date":"2025-03-11T09:57:22","date_gmt":"2025-03-11T12:57:22","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=29022"},"modified":"2026-07-08T09:43:03","modified_gmt":"2026-07-08T12:43:03","slug":"lp-juego-de-conga-santana-apire-de-10-y-11","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/","title":{"rendered":"LP Juego de Conga Santana Apire de 10&#8243; y 11&#8243;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/pCRTs2GBCXA?si=eWx1OBNV5HC9r-XH\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<div class=\"heading-6 product-description\">\n<p>Latin Percussion se enorgullece de la larga relaci\u00f3n con Carlos Santana y se siente honrado de ofrecer este set de conga Aspire Black Magic. Este juego especial de conga Black Magic Oak cuenta con cabezas de cuero crudo natural, llantas EZ Curve, orejetas de afinaci\u00f3n de 9\/32&#8243; de di\u00e1metro, placas laterales de coraz\u00f3n LP Aspire y herrajes negros. Se incluye un soporte doble. *<\/p>\n<\/div>\n<p><span class=\"heading-6 pb-2\">Funciones:<\/span><\/p>\n<ul class=\"heading-6 list-inside list-disc pl-3\">\n<li class=\"pb-2\">Conchas de roble Siam de 28&#8243; de altura con acabado Black Magic Sparkle<\/li>\n<li class=\"pb-2\">Cabezas de cuero crudo de 10&#8243; y 11&#8243;<\/li>\n<li class=\"pb-2\">Herrajes con recubrimiento de polvo negro<\/li>\n<li class=\"pb-2\">Orejetas de 9\/32&#8243; de di\u00e1metro<\/li>\n<li class=\"pb-2\">Soporte de conga doble y llave de afinaci\u00f3n incluidos<\/li>\n<\/ul>\n","protected":false},"featured_media":29027,"template":"","meta":[],"pwb-brand":[381],"product_brand":[],"product_cat":[177,68,413],"product_tag":[5479],"class_list":["post-29022","product","type-product","status-publish","has-post-thumbnail","pwb-brand-lp","product_cat-baterias","product_cat-instrumentos-musicales","product_cat-percusiones","product_tag-lp_0626","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LP Juego de Conga Santana Apire de 10&quot; y 11&quot; - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LP Juego de Conga Santana Apire de 10&quot; y 11&quot; - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Latin Percussion se enorgullece de la larga relaci\u00f3n con Carlos Santana y se siente honrado de ofrecer este set de conga Aspire Black Magic. Este juego especial de conga Black Magic Oak cuenta con cabezas de cuero crudo natural, llantas EZ Curve, orejetas de afinaci\u00f3n de 9\/32&quot; de di\u00e1metro, placas laterales de coraz\u00f3n LP Aspire y herrajes negros. Se incluye un soporte doble. *   Funciones:   Conchas de roble Siam de 28&quot; de altura con acabado Black Magic Sparkle  Cabezas de cuero crudo de 10&quot; y 11&quot;  Herrajes con recubrimiento de polvo negro  Orejetas de 9\/32&quot; de di\u00e1metro  Soporte de conga doble y llave de afinaci\u00f3n incluidos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:43:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/LPA646-BM.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LP Juego de Conga Santana Apire de 10\" y 11\" - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/","og_locale":"es_ES","og_type":"article","og_title":"LP Juego de Conga Santana Apire de 10\" y 11\" - Music Hall","og_description":"Latin Percussion se enorgullece de la larga relaci\u00f3n con Carlos Santana y se siente honrado de ofrecer este set de conga Aspire Black Magic. Este juego especial de conga Black Magic Oak cuenta con cabezas de cuero crudo natural, llantas EZ Curve, orejetas de afinaci\u00f3n de 9\/32\" de di\u00e1metro, placas laterales de coraz\u00f3n LP Aspire y herrajes negros. Se incluye un soporte doble. *   Funciones:   Conchas de roble Siam de 28\" de altura con acabado Black Magic Sparkle  Cabezas de cuero crudo de 10\" y 11\"  Herrajes con recubrimiento de polvo negro  Orejetas de 9\/32\" de di\u00e1metro  Soporte de conga doble y llave de afinaci\u00f3n incluidos","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:43:03+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/LPA646-BM.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/","name":"LP Juego de Conga Santana Apire de 10\" y 11\" - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/LPA646-BM.webp","datePublished":"2025-03-11T12:57:22+00:00","dateModified":"2026-07-08T12:43:03+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/LPA646-BM.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/LPA646-BM.webp","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/lp-juego-de-conga-santana-apire-de-10-y-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"LP Juego de Conga Santana Apire de 10&#8243; y 11&#8243;"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":381,"name":"Latin Percussion","slug":"lp"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/29022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/29027"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=29022"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=29022"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=29022"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=29022"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=29022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}