{"id":29096,"date":"2025-03-11T16:44:16","date_gmt":"2025-03-11T19:44:16","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=29096"},"modified":"2026-07-08T09:43:04","modified_gmt":"2026-07-08T12:43:04","slug":"guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/","title":{"rendered":"Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/j98aIdcouTE?si=1MELVkr_M3-05Nx6\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>El\u00a0<strong>Wolfgang\u00ae WG Standard QM<\/strong>\u00a0cuenta con el mismo estilo y sonido masivo que cre\u00f3 Eddie Van Halen, a un precio que el m\u00fasico cotidiano puede permitirse.<\/p>\n<p>Ofreciendo muchas de las caracter\u00edsticas deslumbrantes como sus hermanas m\u00e1s caras, esta hacha cuenta con un cuerpo de tilo con un contorno especial de antebrazo de &#8220;corte c\u00f3modo&#8221; para una m\u00e1xima facilidad de juego, junto con un atractivo cuerpo natural enmascarado y una elegante tapa de arce acolchado. Su m\u00e1stil de arce horneado atornillado con varillas de refuerzo de grafito se mantiene firme contra los estragos de la temperatura y la humedad, mientras que una rueda de radios convenientemente ubicada en la base del m\u00e1stil permite ajustes r\u00e1pidos e indoloros del alma. Dise\u00f1ado para una ejecuci\u00f3n c\u00f3moda y velocidad, el Wolfgang WG Standard tambi\u00e9n cuenta con un acabado aceitado suave en la parte posterior del m\u00e1stil y un diapas\u00f3n de arce horneado de radio compuesto de 12&#8243;-16&#8243; con bordes enrollados, 22 trastes jumbo e incrustaciones de puntos negros.<\/p>\n<p>Las pastillas humbucking dobles EVH\u00ae Wolfgang montadas directamente en el cuerpo aumentan la transferencia de vibraciones, lo que resulta en un sustain durante d\u00edas y d\u00edas. Los mandos de control de tono y volumen moleteados en negro se han ajustado a las exigentes especificaciones de Van Halen: los potenci\u00f3metros de 500k de sensaci\u00f3n suave facilitan la b\u00fasqueda de un sonido \u00fanico al tiempo que conservan el brillo n\u00edtido de los agudos de las pastillas Wolfgang. El puente Floyd Rose\u00ae Special de la marca EVH y la tuerca de bloqueo R2 mantienen constantemente el instrumento afinado a trav\u00e9s de las inmersiones m\u00e1s profundas y los relinchos de los caballos.<\/p>\n<p>Probado en vivo en el escenario donde cuenta, el Wolfgang WG Standard QM est\u00e1 dise\u00f1ado para el rendimiento y la comodidad de la interpretaci\u00f3n, y est\u00e1 disponible en una variedad de acabados que roban el escenario con clavijeros negros y herrajes cromados negros.<\/p>\n","protected":false},"featured_media":29097,"template":"","meta":[],"pwb-brand":[834],"product_brand":[],"product_cat":[79,74,68],"product_tag":[],"class_list":["post-29096","product","type-product","status-publish","has-post-thumbnail","pwb-brand-evh-brand-guitars","product_cat-guitarras","product_cat-guitarras-electricas","product_cat-instrumentos-musicales","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade - Music Hall\" \/>\n<meta property=\"og:description\" content=\"El\u00a0Wolfgang\u00ae WG Standard QM\u00a0cuenta con el mismo estilo y sonido masivo que cre\u00f3 Eddie Van Halen, a un precio que el m\u00fasico cotidiano puede permitirse.  Ofreciendo muchas de las caracter\u00edsticas deslumbrantes como sus hermanas m\u00e1s caras, esta hacha cuenta con un cuerpo de tilo con un contorno especial de antebrazo de &quot;corte c\u00f3modo&quot; para una m\u00e1xima facilidad de juego, junto con un atractivo cuerpo natural enmascarado y una elegante tapa de arce acolchado. Su m\u00e1stil de arce horneado atornillado con varillas de refuerzo de grafito se mantiene firme contra los estragos de la temperatura y la humedad, mientras que una rueda de radios convenientemente ubicada en la base del m\u00e1stil permite ajustes r\u00e1pidos e indoloros del alma. Dise\u00f1ado para una ejecuci\u00f3n c\u00f3moda y velocidad, el Wolfgang WG Standard tambi\u00e9n cuenta con un acabado aceitado suave en la parte posterior del m\u00e1stil y un diapas\u00f3n de arce horneado de radio compuesto de 12&quot;-16&quot; con bordes enrollados, 22 trastes jumbo e incrustaciones de puntos negros.  Las pastillas humbucking dobles EVH\u00ae Wolfgang montadas directamente en el cuerpo aumentan la transferencia de vibraciones, lo que resulta en un sustain durante d\u00edas y d\u00edas. Los mandos de control de tono y volumen moleteados en negro se han ajustado a las exigentes especificaciones de Van Halen: los potenci\u00f3metros de 500k de sensaci\u00f3n suave facilitan la b\u00fasqueda de un sonido \u00fanico al tiempo que conservan el brillo n\u00edtido de los agudos de las pastillas Wolfgang. El puente Floyd Rose\u00ae Special de la marca EVH y la tuerca de bloqueo R2 mantienen constantemente el instrumento afinado a trav\u00e9s de las inmersiones m\u00e1s profundas y los relinchos de los caballos.  Probado en vivo en el escenario donde cuenta, el Wolfgang WG Standard QM est\u00e1 dise\u00f1ado para el rendimiento y la comodidad de la interpretaci\u00f3n, y est\u00e1 disponible en una variedad de acabados que roban el escenario con clavijeros negros y herrajes cromados negros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:43:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/5107004524E-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/","og_locale":"es_ES","og_type":"article","og_title":"Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade - Music Hall","og_description":"El\u00a0Wolfgang\u00ae WG Standard QM\u00a0cuenta con el mismo estilo y sonido masivo que cre\u00f3 Eddie Van Halen, a un precio que el m\u00fasico cotidiano puede permitirse.  Ofreciendo muchas de las caracter\u00edsticas deslumbrantes como sus hermanas m\u00e1s caras, esta hacha cuenta con un cuerpo de tilo con un contorno especial de antebrazo de \"corte c\u00f3modo\" para una m\u00e1xima facilidad de juego, junto con un atractivo cuerpo natural enmascarado y una elegante tapa de arce acolchado. Su m\u00e1stil de arce horneado atornillado con varillas de refuerzo de grafito se mantiene firme contra los estragos de la temperatura y la humedad, mientras que una rueda de radios convenientemente ubicada en la base del m\u00e1stil permite ajustes r\u00e1pidos e indoloros del alma. Dise\u00f1ado para una ejecuci\u00f3n c\u00f3moda y velocidad, el Wolfgang WG Standard tambi\u00e9n cuenta con un acabado aceitado suave en la parte posterior del m\u00e1stil y un diapas\u00f3n de arce horneado de radio compuesto de 12\"-16\" con bordes enrollados, 22 trastes jumbo e incrustaciones de puntos negros.  Las pastillas humbucking dobles EVH\u00ae Wolfgang montadas directamente en el cuerpo aumentan la transferencia de vibraciones, lo que resulta en un sustain durante d\u00edas y d\u00edas. Los mandos de control de tono y volumen moleteados en negro se han ajustado a las exigentes especificaciones de Van Halen: los potenci\u00f3metros de 500k de sensaci\u00f3n suave facilitan la b\u00fasqueda de un sonido \u00fanico al tiempo que conservan el brillo n\u00edtido de los agudos de las pastillas Wolfgang. El puente Floyd Rose\u00ae Special de la marca EVH y la tuerca de bloqueo R2 mantienen constantemente el instrumento afinado a trav\u00e9s de las inmersiones m\u00e1s profundas y los relinchos de los caballos.  Probado en vivo en el escenario donde cuenta, el Wolfgang WG Standard QM est\u00e1 dise\u00f1ado para el rendimiento y la comodidad de la interpretaci\u00f3n, y est\u00e1 disponible en una variedad de acabados que roban el escenario con clavijeros negros y herrajes cromados negros.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:43:04+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/5107004524E-scaled.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/","name":"Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/5107004524E-scaled.webp","datePublished":"2025-03-11T19:44:16+00:00","dateModified":"2026-07-08T12:43:04+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/5107004524E-scaled.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/03\/5107004524E-scaled.webp","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/guitarra-electrica-evh-wolfgang-wg-standard-qm-black-fade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Guitarra El\u00e9ctrica EVH Wolfgang WG Standard QM Black Fade"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":834,"name":"EVH Brand Guitars","slug":"evh-brand-guitars"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/29096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/29097"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=29096"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=29096"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=29096"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=29096"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=29096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}