{"id":31231,"date":"2025-07-21T09:54:40","date_gmt":"2025-07-21T12:54:40","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=31231"},"modified":"2026-07-08T09:43:17","modified_gmt":"2026-07-08T12:43:17","slug":"roland-black-series-interconnect-cable-rcc-5-2r28-1-5m","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/","title":{"rendered":"Roland Black Series Interconnect Cable RCC-5-2R28 1.5M"},"content":{"rendered":"<ul>\n<li><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\" data-number-of-phrases=\"7\"><span class=\"Q4iAWc\">Conectores de servicio pesado.<\/span><\/span><\/li>\n<li><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"2\" data-number-of-phrases=\"7\"><span class=\"Q4iAWc\">Blindaje de cobre en espiral de alta densidad.<\/span><\/span><\/li>\n<li><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"4\" data-number-of-phrases=\"7\"><span class=\"Q4iAWc\">El dise\u00f1o de baja capacitancia garantiza una reproducci\u00f3n de frecuencia completa y una respuesta din\u00e1mica m\u00e1xima.<\/span><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\" data-number-of-phrases=\"3\"><span class=\"Q4iAWc\">Los cables de interconexi\u00f3n de la serie Black de Roland ofrecen un rendimiento profesional y un valor excepcional.<\/span><\/span> <span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"1\" data-number-of-phrases=\"3\"><span class=\"Q4iAWc\">El cable de n\u00facleo de cobre libre de ox\u00edgeno de m\u00faltiples hilos y el blindaje en espiral de alta densidad garantizan una transferencia de se\u00f1al perfecta para conectar pedales, instrumentos, equipos de estudio y m\u00e1s.<\/span><\/span> <span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"es\" data-language-to-translate-into=\"en\" data-phrase-index=\"2\" data-number-of-phrases=\"3\"><span class=\"Q4iAWc\">Con conectores de alta calidad y un dise\u00f1o de baja capacitancia, estos cables brindan un funcionamiento confiable y un sonido superior para cada conexi\u00f3n de equipo en su equipo.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":13869,"template":"","meta":[],"pwb-brand":[404],"product_brand":[],"product_cat":[145,2405,150],"product_tag":[5459],"class_list":["post-31231","product","type-product","status-publish","has-post-thumbnail","pwb-brand-roland","product_cat-accesorios","product_cat-audio-pro","product_cat-cables","product_tag-novedades030326","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roland Black Series Interconnect Cable RCC-5-2R28 1.5M - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland Black Series Interconnect Cable RCC-5-2R28 1.5M - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Los cables de interconexi\u00f3n de la serie Black de Roland ofrecen un rendimiento profesional y un valor excepcional. El cable de n\u00facleo de cobre libre de ox\u00edgeno de m\u00faltiples hilos y el blindaje en espiral de alta densidad garantizan una transferencia de se\u00f1al perfecta para conectar pedales, instrumentos, equipos de estudio y m\u00e1s. Con conectores de alta calidad y un dise\u00f1o de baja capacitancia, estos cables brindan un funcionamiento confiable y un sonido superior para cada conexi\u00f3n de equipo en su equipo.  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4CABRORCC-10-2R28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roland Black Series Interconnect Cable RCC-5-2R28 1.5M - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/","og_locale":"es_ES","og_type":"article","og_title":"Roland Black Series Interconnect Cable RCC-5-2R28 1.5M - Music Hall","og_description":"Los cables de interconexi\u00f3n de la serie Black de Roland ofrecen un rendimiento profesional y un valor excepcional. El cable de n\u00facleo de cobre libre de ox\u00edgeno de m\u00faltiples hilos y el blindaje en espiral de alta densidad garantizan una transferencia de se\u00f1al perfecta para conectar pedales, instrumentos, equipos de estudio y m\u00e1s. Con conectores de alta calidad y un dise\u00f1o de baja capacitancia, estos cables brindan un funcionamiento confiable y un sonido superior para cada conexi\u00f3n de equipo en su equipo.  &nbsp;","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:43:17+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4CABRORCC-10-2R28.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/","name":"Roland Black Series Interconnect Cable RCC-5-2R28 1.5M - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4CABRORCC-10-2R28.jpg","datePublished":"2025-07-21T12:54:40+00:00","dateModified":"2026-07-08T12:43:17+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4CABRORCC-10-2R28.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2022\/04\/4CABRORCC-10-2R28.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/roland-black-series-interconnect-cable-rcc-5-2r28-1-5m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Roland Black Series Interconnect Cable RCC-5-2R28 1.5M"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":404,"name":"Roland","slug":"roland"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/31231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/13869"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=31231"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=31231"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=31231"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=31231"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=31231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}