{"id":31433,"date":"2025-08-05T08:34:53","date_gmt":"2025-08-05T11:34:53","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=31433"},"modified":"2026-07-08T09:43:17","modified_gmt":"2026-07-08T12:43:17","slug":"reproductor-de-audio-streamer-wiim-pro","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/","title":{"rendered":"Reproductor de audio Streamer &#8211; WiiM Pro"},"content":{"rendered":"<p><strong>Compatibilidad<\/strong><\/p>\n<p>Resuelva problemas de compatibilidad con algunos DAC (de gama baja) que no manejan correctamente el reloj, la frecuencia de muestreo\/profundidad de bits variables o que no admiten una entrada digital de hasta 24 bits\/192 kHz.<\/p>\n<p>WiiM Pro Plus es una mejora significativa en t\u00e9rminos de calidad de audio para entrada y salida de audio anal\u00f3gico, coste total del sistema y configuraci\u00f3n del sistema. Estas mejoras tienen como objetivo brindar a los usuarios una experiencia de streaming de m\u00fasica m\u00e1s potente, de alta fidelidad y sin complicaciones en comparaci\u00f3n con el modelo anterior, el WiiM Pro.<\/p>\n<p><strong>DIFERENCIAS ENTRE EL WIIM PRO Y EL WIIM PRO PLUS<\/strong><\/p>\n<p><strong>Mejor Conversor Anal\u00f3gico \/ Digital para entrada de l\u00ednea<\/strong><\/p>\n<p>Utiliza el conversor Anal\u00f3gico \/ Digital Texas Instruments Burr-Brown Audio PCM1861, logrando una salida digital de hasta 192 kHz \/ 32 bits y relaci\u00f3n Se\u00f1al\/Ruido 110 dB. Por lo tanto, proporciona conversi\u00f3n anal\u00f3gica a digital de alta fidelidad para la entrada desde un tocadiscos, un reproductor de MP3 o un televisor.<\/p>\n<p><strong>Dise\u00f1o de circuito, potencia y reloj con ruido ultrabajo<\/strong><\/p>\n<p>Utiliza un reloj de ruido ultrabajo, una fuente de alimentaci\u00f3n y un cuidadoso dise\u00f1o de PCB para lograr un rendimiento de distorsi\u00f3n arm\u00f3nica total + ruido (THD+N) inferior a \u2013110 dB para salida de audio anal\u00f3gico.<\/p>\n<p><strong>DAC de AKM y amplificador operacional Texas Instruments para una mejor calidad de audio de salida de l\u00ednea<\/strong><\/p>\n<p>Cuenta con un DAC premium AKM 4493SEQ de nueva generaci\u00f3n que es capaz de lograr un nivel l\u00edder de baja distorsi\u00f3n y un amplio rango din\u00e1mico gracias a la tecnolog\u00eda Velvet Sound de AKM. Admite PCM de hasta 768 kHz, ideal para la \u00faltima fuente de audio de alta resoluci\u00f3n. Logre una Relaci\u00f3n Se\u00f1al\/Ruido de 120 dB (ponderado A), distorsi\u00f3n arm\u00f3nica total (THD+N) de 0,00032% (-110 dB) de 44,1 kHz a 192 kHz.<\/p>\n<p><strong>Configuraci\u00f3n s\u00faper f\u00e1cil<\/strong><\/p>\n<p>WiiM Pro aparecer\u00e1 autom\u00e1ticamente en la aplicaci\u00f3n WiiM Home. Siga la gu\u00eda de la aplicaci\u00f3n y comience a transmitir m\u00fasica en menos de 2 minutos.<\/p>\n<p><strong>Calidad de sonido inigualable hasta 192 kHz\/24 bits<\/strong><\/p>\n<p>A diferencia de la norma de remuestreo para establecer la frecuencia de muestreo y la profundidad de bits, WiiM Pro se destaca por ofrecer audio inalterado de hasta 192 kHz y calidad de 24 bits. Eso es lo mismo que la grabaci\u00f3n de un artista en el estudio. El avanzado DAC Texas Instruments PCM5121 produce una notable Relaci\u00f3n Se\u00f1al\/Ruido de 106 dB y un impresionante rendimiento distorsi\u00f3n arm\u00f3nica total (THD+N) de -92 dB.<\/p>\n<p><strong>Todo tu contenido en una sola aplicaci\u00f3n<\/strong><\/p>\n<p>Admitimos muchos servicios populares de streaming de m\u00fasica en nuestra aplicaci\u00f3n WiiM Home y habr\u00e1 m\u00e1s por venir. O con\u00e9ctese a su NAS o archivos locales para transmitir su m\u00fasica favorita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.studio-22.com\/media\/\/wysiwyg\/productos\/WiiM_Pro_01.JPG\" alt=\"\" width=\"900\" height=\"352\" \/><\/p>\n<p><strong>Spotify Connect<\/strong><\/p>\n<p>Utilice su aplicaci\u00f3n Spotify como control remoto para WiiM Pro y transmita directamente desde Spotify Cloud, funciona tanto para usuarios de Spotify Free como Premium.<\/p>\n<p><strong>AirPlay 2<\/strong><\/p>\n<p>Transmita audio desde iPhone, iPad, ordenador Mac o Apple TV a uno o varios dispositivos de audio al mismo tiempo. Utilice Siri en su tel\u00e9fono smartphone o HomePod para controlar la selecci\u00f3n, el volumen y la reproducci\u00f3n de m\u00fasica.<\/p>\n<p><strong>Chromecast<\/strong><\/p>\n<p>Transmita m\u00fasica, audio de TV, estaciones de radio, podcasts y contenido local desde aplicaciones habilitadas para Chromecast a uno o varios dispositivos de audio al mismo tiempo. Utilice el asistente de voz de Google en su tel\u00e9fono smartphone, altavoz y televisor para controlar la reproducci\u00f3n de m\u00fasica.<\/p>\n<p><strong>Tidal Connect<\/strong><\/p>\n<p>Usa tu aplicaci\u00f3n TIDAL como control remoto para controlar la reproducci\u00f3n de m\u00fasica a trav\u00e9s de WiiM Pro.<\/p>\n<p><strong>DLNA<\/strong><\/p>\n<p>Utilice WiiM Pro como receptor DLNA y transmita m\u00fasica desde su propio servidor en la nube, PC o NAS.<\/p>\n<p><strong>Alexa Cast<\/strong><\/p>\n<p>Reproduzca m\u00fasica con otros dispositivos Alexa en un grupo o use la voz para controlarla desde otro dispositivo integrado de Alexa.<\/p>\n<p><strong>Roon Ready<\/strong><\/p>\n<p>Utilice su aplicaci\u00f3n Roon como control remoto para controlar la reproducci\u00f3n de m\u00fasica a trav\u00e9s de WiiM Pro.<\/p>\n<p><strong>Reproduzca m\u00fasica en todas partes con audio multisala<\/strong><\/p>\n<p>Construya f\u00e1cilmente su sistema de sonido multisala con sus altavoces AirPlay 2 existentes, Amazon Echo y dispositivos Google Home. Con sus dispositivos de audio heredados, puede crear un sistema de sonido multisala m\u00e1s flexible con m\u00faltiples dispositivos WiiM Pros, WiiM Minis o Linkplay. WiiM Pro admite multisala desde varias entradas de fuentes de audio, incluidas entradas WiFi, Bluetooth, entrada auxiliar minijack 3.5 mm y entrada digital \u00f3ptica SPDIF, lo que lo hace vers\u00e1til con casi todas las opciones para escuchar m\u00fasica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.studio-22.com\/media\/\/wysiwyg\/productos\/WiiM_Pro_02.jpg\" alt=\"\" width=\"800\" height=\"480\" \/><\/p>\n<p><strong>M\u00faltiples opciones de ecualizador<\/strong><\/p>\n<p>Satisfaga sus gustos auditivos aplicando m\u00faltiples opciones de ecualizaci\u00f3n, incluidos 26 ecualizadores preestablecidos, ajuste de graves\/agudos, ecualizador gr\u00e1fico de 10 bandas y ecualizador param\u00e9trico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.studio-22.com\/media\/\/wysiwyg\/productos\/WiiM_Pro_03.jpg\" alt=\"\" width=\"800\" height=\"378\" \/><\/p>\n<p><strong>Automatiza tus rutinas<\/strong><\/p>\n<p>Haz tu vida m\u00e1s f\u00e1cil automatizando tus rutinas. Para sus rutinas de dormir y despertar, cree una rutina para despertarse o quedarse dormido con su m\u00fasica, estaci\u00f3n o podcasts favoritos. O usa tu Alexa para crear rutinas.<\/p>\n<p><strong>Funciona con Siri, Alexa y asistente de voz de Google<\/strong><\/p>\n<p>Utilice sus asistentes de voz favoritos para seleccionar m\u00fasica, controlar el volumen de reproducci\u00f3n y m\u00e1s.<\/p>\n<p><strong>TECNOLOG\u00cdA<\/strong><\/p>\n<p><strong>High-Res Audio<\/strong><\/p>\n<p>Ofreciendo m\u00e1s servicios de streaming y contenidos de audio que incorporen calidad MP3, audio sin p\u00e9rdidas o tecnolog\u00edas de sonido inmersivo para sus oyentes. Los dispositivos WiiM brindan la capacidad de reproducir contenidos de audio de alta resoluci\u00f3n sin p\u00e9rdidas de Spotify, Amazon Music, TIDAL, Deezer, Qobuz y m\u00e1s. Admite salida de audio de hasta 192 kHz y 24 bits, que es la misma que la grabaci\u00f3n del artista en el estudio. El DAC est\u00e9reo Texas Instruments integrado proporciona una salida de audio anal\u00f3gico de alta calidad con Relaci\u00f3n Se\u00f1al\/Ruido de 106 dB, rango din\u00e1mico y rendimiento distorsi\u00f3n arm\u00f3nica total (THD+N) de -92 dB, excepcional en todas las categor\u00edas de audio.<\/p>\n<p><strong>Emparejamiento multisala y est\u00e9reo<\/strong><\/p>\n<p>La reproducci\u00f3n de m\u00fasica en toda la casa se logra con la sincronizaci\u00f3n de audio perfecta y el control perfecto del dispositivo a trav\u00e9s de la aplicaci\u00f3n complementaria. Con una cuidadosa optimizaci\u00f3n del hardware, los algoritmos y el software, podemos lograr una precisi\u00f3n de sincronizaci\u00f3n inferior a 150 \u03bcs (0,00015 s) entre los altavoces, siempre que est\u00e9n en la misma red inal\u00e1mbrica. As\u00ed, tu sistema de altavoces podr\u00e1 ubicarse dondequiera que cubra tu red Wi-Fi.<\/p>\n<p>Adem\u00e1s, puedes unir dos altavoces conectados con WiiM Pro o Mini como un par est\u00e9reo para un escenario sonoro m\u00e1s amplio y envolvente. Tambi\u00e9n es compatible con varias habitaciones y con diversas entradas de audio, como streaming de m\u00fasica basada en Wi-Fi, BT y entrada de audio anal\u00f3gico\/digital a trav\u00e9s de Line In o entrada \u00f3ptica. Por lo tanto, puede funcionar con la mayor\u00eda de sus opciones para escuchar m\u00fasica.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.studio-22.com\/media\/\/wysiwyg\/productos\/WiiM_Pro_04.jpg\" alt=\"\" width=\"499\" height=\"597\" \/><\/p>\n<p><strong>Reproducci\u00f3n sin pausas<\/strong><\/p>\n<p>La reproducci\u00f3n precisa y sin interrupciones es importante para su experiencia auditiva. Con una reproducci\u00f3n precisa y sin interrupciones, se garantiza que el tiempo de reproducci\u00f3n ser\u00e1 id\u00e9ntico al de la fuente. No est\u00e1 permitido introducir huecos ni superposiciones (crossfading) entre pistas sucesivas. La brecha ser\u00e1 muy notable en la m\u00fasica &#8220;continua&#8221;, como la grabaci\u00f3n de conciertos en vivo, algo de m\u00fasica cl\u00e1sica, etc.<\/p>\n<p>Varios componentes de software, firmware y hardware pueden sumar un retraso sustancial asociado con el inicio de la reproducci\u00f3n de la pista. Nuestro reproductor utiliza dos decodificadores para eliminar las muestras adicionales al principio y al final de cada archivo y combinarlas. Funciona para todos los servicios de m\u00fasica compatibles y m\u00fasica en su tel\u00e9fono smartphone o red local.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.studio-22.com\/media\/\/wysiwyg\/productos\/WiiM_Pro_05.jpg\" alt=\"\" width=\"502\" height=\"341\" \/><\/p>\n<p><strong>Ecualizador adaptativo<\/strong><\/p>\n<p>Una experiencia auditiva innovadora requiere contenidos de audio de alta resoluci\u00f3n y un dispositivo de reproducci\u00f3n de alta calidad. Cuando el ecualizador adaptativo est\u00e1 habilitado, la informaci\u00f3n del g\u00e9nero musical y otras etiquetas incluidas en el contenido de audio se utilizan para ajustar la frecuencia en tiempo real, ya sea brindando un audio rico para capturar cada detalle de la m\u00fasica o haciendo que las voces humanas sean m\u00e1s claras en el podcast.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.studio-22.com\/media\/\/wysiwyg\/productos\/WiiM_Pro_07.jpg\" alt=\"\" width=\"496\" height=\"455\" \/><\/p>\n<p><strong>Calibraci\u00f3n autom\u00e1tica del retardo de audio<\/strong><\/p>\n<p>El receptor o altavoz conectado puede tener una latencia de ruta de audio diferente debido a diferentes hardware, software y procesamiento DSP. Para mantener la sincronizaci\u00f3n de cada sistema, es deseable medir el retardo de la ruta de audio autom\u00e1ticamente. Al aprovechar el micr\u00f3fono del dispositivo y el algoritmo patentado, toda la latencia de la ruta de audio se mide autom\u00e1ticamente cuando se conecta con el receptor o el altavoz. El valor de latencia se utilizar\u00e1 para mantener la perfecta sincronizaci\u00f3n de audio en la reproducci\u00f3n inal\u00e1mbrica en varias habitaciones con HomePod, Echo, Google Home u otros dispositivos WiiM.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><video controls=\"controls\" width=\"100%\" height=\"100%\"><source src=\"https:\/\/www.wiimhome.com\/wiimpro\/assets\/full_pro_video-10iGyGCu.mp4\" \/><\/video><\/p>\n<p><strong>Wiim Pro: El Streamer audi\u00f3filo vers\u00e1til<\/strong><\/p>\n<p><strong>Simplifica tu sistema de HiFi<\/strong><\/p>\n<p>Directo a su amplificador o altavoz activo sin DAC externo.<br \/>\nLa calidad del audio es comparable con la de WiiM Mini conectado a un DAC externo de alta fidelidad.<\/p>\n<p><strong>Calidad de sonido para entradas anal\u00f3gicas<\/strong><\/p>\n<p>La mejor calidad de audio para fuentes de entrada anal\u00f3gicas.<\/p>\n","protected":false},"featured_media":31439,"template":"","meta":[],"pwb-brand":[5378],"product_brand":[],"product_cat":[422,5379],"product_tag":[5469],"class_list":["post-31433","product","type-product","status-publish","has-post-thumbnail","pwb-brand-wiim","product_cat-home-audio","product_cat-streamers","product_tag-novedades_abril26","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reproductor de audio Streamer - WiiM Pro - Music Hall<\/title>\n<meta name=\"description\" content=\"Descubr\u00ed los streamers de audio Wiim. Calidad Hi-Res, AirPlay 2, Spotify Connect y control multiroom desde tu m\u00f3vil. Envios en todo Paraguay\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reproductor de audio Streamer - WiiM Pro - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Descubr\u00ed los streamers de audio Wiim. Calidad Hi-Res, AirPlay 2, Spotify Connect y control multiroom desde tu m\u00f3vil. Envios en todo Paraguay\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/wiimpro.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reproductor de audio Streamer - WiiM Pro - Music Hall","description":"Descubr\u00ed los streamers de audio Wiim. Calidad Hi-Res, AirPlay 2, Spotify Connect y control multiroom desde tu m\u00f3vil. Envios en todo Paraguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/","og_locale":"es_ES","og_type":"article","og_title":"Reproductor de audio Streamer - WiiM Pro - Music Hall","og_description":"Descubr\u00ed los streamers de audio Wiim. Calidad Hi-Res, AirPlay 2, Spotify Connect y control multiroom desde tu m\u00f3vil. Envios en todo Paraguay","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:43:17+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/wiimpro.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/","name":"Reproductor de audio Streamer - WiiM Pro - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/wiimpro.webp","datePublished":"2025-08-05T11:34:53+00:00","dateModified":"2026-07-08T12:43:17+00:00","description":"Descubr\u00ed los streamers de audio Wiim. Calidad Hi-Res, AirPlay 2, Spotify Connect y control multiroom desde tu m\u00f3vil. Envios en todo Paraguay","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/wiimpro.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/wiimpro.webp","width":1920,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/reproductor-de-audio-streamer-wiim-pro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Reproductor de audio Streamer &#8211; WiiM Pro"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":5378,"name":"Wiim","slug":"wiim"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/31433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/31439"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=31433"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=31433"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=31433"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=31433"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=31433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}