{"id":31646,"date":"2025-08-20T09:18:12","date_gmt":"2025-08-20T12:18:12","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=31646"},"modified":"2026-09-01T11:24:48","modified_gmt":"2026-09-01T14:24:48","slug":"laney-lfsuper60-212","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/","title":{"rendered":"Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2&#215;12&#8243;Limited Edition Seafoam Green"},"content":{"rendered":"<p><b>Caracter\u00edsticas:\u00a0<\/b><\/p>\n<ul>\n<li>60W RMS a 8\u03a9(m\u00ednimo)<\/li>\n<li>Selector de potencia Full\/1W<\/li>\n<li>Dos canales seleccionables mediante pedalera<\/li>\n<li>Pre-Boostse puede activar mediante pedalera<\/li>\n<li>Controles independientes de volumen y ganancia por canal<\/li>\n<li>Tres bandas de ecualizador comunes + control de tono general<\/li>\n<li>Selector CLEAN\/RHYTHM\/LEAD para CH1<\/li>\n<li>Selector BRIGHT\/FLAT\/DARK para CH2<\/li>\n<li>Efectos digitales integrados de Tremolo, Chorusy Reverb-Loopde efectos &#8220;TransformerInsulated&#8221;<\/li>\n<li>Salida XLR con emulaci\u00f3n de altavoz LA-IR 1&#215;12&#8243;\/4&#215;12&#8243;<\/li>\n<li>Altavoces CustomDesignHH 1260<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La serie FOUNDRY toma la potencia, el dinamismo y la respuesta de nuestras aclamadas gamas de amplificadores de v\u00e1lvulas y las forja en amplificadores de estado s\u00f3lido creativos, asequibles y de alta calidad que son pr\u00e1cticos, cargados de funciones, port\u00e1tiles y muy divertidos. Tras el gran \u00e9xito de nuestros galardonados amplificadores LIONHEART FOUNDRY, ahora presentamos con orgullo una gama de combos de guitarra Sea Foam Green de edici\u00f3n limitada.<\/p>\n","protected":false},"featured_media":31690,"template":"","meta":[],"pwb-brand":[87],"product_brand":[],"product_cat":[116,115],"product_tag":[5441],"class_list":["post-31646","product","type-product","status-publish","has-post-thumbnail","pwb-brand-laney","product_cat-amp-guitarras","product_cat-amplificadores","product_tag-supersale","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2x12&quot;Limited Edition Seafoam Green - Music Hall<\/title>\n<meta name=\"description\" content=\"La serie FOUNDRY toma la potencia, el dinamismo y la respuesta de nuestras aclamadas gamas de amplificadores de v\u00e1lvulas y las forja en amplificadores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2x12&quot;Limited Edition Seafoam Green - Music Hall\" \/>\n<meta property=\"og:description\" content=\"La serie FOUNDRY toma la potencia, el dinamismo y la respuesta de nuestras aclamadas gamas de amplificadores de v\u00e1lvulas y las forja en amplificadores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:24:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/LFSUPER60-212.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2x12\"Limited Edition Seafoam Green - Music Hall","description":"La serie FOUNDRY toma la potencia, el dinamismo y la respuesta de nuestras aclamadas gamas de amplificadores de v\u00e1lvulas y las forja en amplificadores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/","og_locale":"es_ES","og_type":"article","og_title":"Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2x12\"Limited Edition Seafoam Green - Music Hall","og_description":"La serie FOUNDRY toma la potencia, el dinamismo y la respuesta de nuestras aclamadas gamas de amplificadores de v\u00e1lvulas y las forja en amplificadores","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-09-01T14:24:48+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/LFSUPER60-212.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/","name":"Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2x12\"Limited Edition Seafoam Green - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/LFSUPER60-212.webp","datePublished":"2025-08-20T12:18:12+00:00","dateModified":"2026-09-01T14:24:48+00:00","description":"La serie FOUNDRY toma la potencia, el dinamismo y la respuesta de nuestras aclamadas gamas de amplificadores de v\u00e1lvulas y las forja en amplificadores","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/LFSUPER60-212.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/08\/LFSUPER60-212.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/laney-lfsuper60-212\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Laney LFSUPER60-212 LIONHEART FOUNDRY Series 2&#215;12&#8243;Limited Edition Seafoam Green"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":87,"name":"Laney Amplification","slug":"laney"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/31646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/31690"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=31646"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=31646"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=31646"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=31646"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=31646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}