{"id":33519,"date":"2025-10-24T18:02:56","date_gmt":"2025-10-24T21:02:56","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=33519"},"modified":"2026-07-08T09:43:31","modified_gmt":"2026-07-08T12:43:31","slug":"marshall-ori50h-origin-50-head","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/","title":{"rendered":"Marshall ORI50H Origin 50 Head"},"content":{"rendered":"<h2>Caracter\u00edsticas<\/h2>\n<ul>\n<li>Dise\u00f1ados para ser los amplificadores&#8221;m\u00e1s expresivos&#8221; de Marshall<\/li>\n<li>Amplificador mono canal vintage<\/li>\n<li>Impulsado por el preamplificador ECC83 (12AX7) y las v\u00e1lvulas de potencia EL34 para un verdadero sonido&#8217;brit\u00e1nico<\/li>\n<li>La tecnolog\u00eda de reducci\u00f3n de potencia Powerstem ofrece ajustes de salida de 1W, 10W y 50W.<\/li>\n<li>Potente ecualizador de 3 bandas que proporciona una incre\u00edble formaci\u00f3n del tono<\/li>\n<li>El control de inclinaci\u00f3n permite a los reproductores mezclar el sonido entre las voces normales y las agudas<\/li>\n<li>El control de presencia aumenta las altas frecuencias<\/li>\n<li>El volumen maestro proporciona ese sonido cl\u00e1sico de sobremarcha<\/li>\n<li>El aumento de ganancia conmutable ofrece un nivel extra de ganancia<\/li>\n<\/ul>\n<h2>Especificaciones<\/h2>\n<h3>General<\/h3>\n<ul>\n<li><b>Modelo:<\/b>\u00a0Origen50H<\/li>\n<li><b>Alcance:<\/b>\u00a0Origen<\/li>\n<li><b>Tecnolog\u00eda:<\/b>\u00a0V\u00e1lvula<\/li>\n<li><b>Canales:\u00a0<\/b>1<\/li>\n<li><b>Accesorios:\u00a0<\/b>PEDL-90016 Pedalera, Cable de alimentaci\u00f3n desmontable<\/li>\n<\/ul>\n<h3>Electr\u00f3nica<\/h3>\n<ul>\n<li><b>Potencia de salida:<\/b>\u00a050W<\/li>\n<li><b>Controles:<\/b>\u00a0Ganancia, Realce, Inclinaci\u00f3n, Graves, Medios, Agudos, Master, Presencia, Escala de potencia<\/li>\n<li><b>Salidas:<\/b>\u00a03x 1\/4&#8243; Jack Sockets (carga de 16 ohmios \/ carga de 8 ohmios), DI Out<\/li>\n<li><b>Entradas:<\/b>\u00a01x 1\/4&#8243; Jack Entrada de instrumento, Footswitch<\/li>\n<li><b>Lazo de efectos:<\/b>\u00a0Enviar\/Retornar<\/li>\n<\/ul>\n<h3>V\u00e1lvulas<\/h3>\n<ul>\n<li><b>V\u00e1lvulas de preamplificaci\u00f3n:<\/b>\u00a03x ECC83<\/li>\n<li><b>V\u00e1lvulas de potencia:<\/b>\u00a02 x EL34<\/li>\n<\/ul>\n<h3>Dimensiones<\/h3>\n<ul>\n<li><b>Ancho:<\/b>\u00a0577mm<\/li>\n<li><b>Altura:<\/b>\u00a0228mm<\/li>\n<li><b>Profundidad:<\/b>\u00a0225mm<\/li>\n<li><b>Peso:<\/b>\u00a011.8kg<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Marshall ORI50H Origin 50W Valve Head posee un solo canal y un desempe\u00f1o vintage estilo, entregando su amplificador &#8221;m\u00e1s expresivo&#8221;&#8217;. Sus 50 vatios de potencia de rock&#8217;n&#8217; roll puro accionan las v\u00e1lvulas de preamplificaci\u00f3n ECC83 y las v\u00e1lvulas de potencia EL34, produciendo el cl\u00e1sico car\u00e1cter tonal&#8221;brit\u00e1nico&#8221; y la ruptura. El panel de control intuitivo proporciona a los instrumentistas excelentes capacidades de configuraci\u00f3n de tono, ofreciendo un ecualizador de 3 bandas, controles de inclinaci\u00f3n, aumento de tiro y presencia para marcar en tonos cl\u00e1sicos de Marshall. El amplificador Origin Amplificador Head de 50W tambi\u00e9n est\u00e1 equipado con un interruptor de salida de potencia de 3 posiciones, que ofrece la posibilidad de elegir entre 1W, 10W y 50W de potencia para mantener la saturaci\u00f3n de la v\u00e1lvula cl\u00e1sica a cualquier volumen. El Marshall ORI50H Amplificador Head tambi\u00e9n cuenta con un loop FX, salida D.I. emulada, capacidades de pedalera y una selecci\u00f3n de salidas de altavoz para conectar 8 ohmios y cajas ac\u00fasticas de 16 ohmios.<\/p>\n","protected":false},"featured_media":33523,"template":"","meta":[],"pwb-brand":[120],"product_brand":[],"product_cat":[116],"product_tag":[],"class_list":["post-33519","product","type-product","status-publish","has-post-thumbnail","pwb-brand-marshall","product_cat-amp-guitarras","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marshall ORI50H Origin 50 Head - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marshall ORI50H Origin 50 Head - Music Hall\" \/>\n<meta property=\"og:description\" content=\"El Marshall ORI50H Origin 50W Valve Head posee un solo canal y un desempe\u00f1o vintage estilo, entregando su amplificador &#039;&#039;m\u00e1s expresivo&#039;&#039;&#039;. Sus 50 vatios de potencia de rock&#039;n&#039; roll puro accionan las v\u00e1lvulas de preamplificaci\u00f3n ECC83 y las v\u00e1lvulas de potencia EL34, produciendo el cl\u00e1sico car\u00e1cter tonal&quot;brit\u00e1nico&quot; y la ruptura. El panel de control intuitivo proporciona a los instrumentistas excelentes capacidades de configuraci\u00f3n de tono, ofreciendo un ecualizador de 3 bandas, controles de inclinaci\u00f3n, aumento de tiro y presencia para marcar en tonos cl\u00e1sicos de Marshall. El amplificador Origin Amplificador Head de 50W tambi\u00e9n est\u00e1 equipado con un interruptor de salida de potencia de 3 posiciones, que ofrece la posibilidad de elegir entre 1W, 10W y 50W de potencia para mantener la saturaci\u00f3n de la v\u00e1lvula cl\u00e1sica a cualquier volumen. El Marshall ORI50H Amplificador Head tambi\u00e9n cuenta con un loop FX, salida D.I. emulada, capacidades de pedalera y una selecci\u00f3n de salidas de altavoz para conectar 8 ohmios y cajas ac\u00fasticas de 16 ohmios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/10\/ORI50H-E.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marshall ORI50H Origin 50 Head - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/","og_locale":"es_ES","og_type":"article","og_title":"Marshall ORI50H Origin 50 Head - Music Hall","og_description":"El Marshall ORI50H Origin 50W Valve Head posee un solo canal y un desempe\u00f1o vintage estilo, entregando su amplificador ''m\u00e1s expresivo'''. Sus 50 vatios de potencia de rock'n' roll puro accionan las v\u00e1lvulas de preamplificaci\u00f3n ECC83 y las v\u00e1lvulas de potencia EL34, produciendo el cl\u00e1sico car\u00e1cter tonal\"brit\u00e1nico\" y la ruptura. El panel de control intuitivo proporciona a los instrumentistas excelentes capacidades de configuraci\u00f3n de tono, ofreciendo un ecualizador de 3 bandas, controles de inclinaci\u00f3n, aumento de tiro y presencia para marcar en tonos cl\u00e1sicos de Marshall. El amplificador Origin Amplificador Head de 50W tambi\u00e9n est\u00e1 equipado con un interruptor de salida de potencia de 3 posiciones, que ofrece la posibilidad de elegir entre 1W, 10W y 50W de potencia para mantener la saturaci\u00f3n de la v\u00e1lvula cl\u00e1sica a cualquier volumen. El Marshall ORI50H Amplificador Head tambi\u00e9n cuenta con un loop FX, salida D.I. emulada, capacidades de pedalera y una selecci\u00f3n de salidas de altavoz para conectar 8 ohmios y cajas ac\u00fasticas de 16 ohmios.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:43:31+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/10\/ORI50H-E.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/","name":"Marshall ORI50H Origin 50 Head - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/10\/ORI50H-E.webp","datePublished":"2025-10-24T21:02:56+00:00","dateModified":"2026-07-08T12:43:31+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/10\/ORI50H-E.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/10\/ORI50H-E.webp","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/marshall-ori50h-origin-50-head\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Marshall ORI50H Origin 50 Head"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":120,"name":"Marshall","slug":"marshall"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/33519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/33523"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=33519"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=33519"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=33519"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=33519"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=33519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}