{"id":34951,"date":"2026-03-06T10:27:05","date_gmt":"2026-03-06T13:27:05","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=34951"},"modified":"2026-09-01T11:25:21","modified_gmt":"2026-09-01T14:25:21","slug":"cable-de-altavoz-boss-bsc-5-15m","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/","title":{"rendered":"Cable de altavoz Boss BSC-5 &#8211; 1,5M"},"content":{"rendered":"<ul class=\"vertical\">\n<li>Cable de altavoz robusto para amplificadores de guitarra y bajo<\/li>\n<li>Contactos ba\u00f1ados en oro de 24K para una vida \u00fatil libre de corrosi\u00f3n<\/li>\n<li>El cable de n\u00facleo de cobre de grosor (14AWG) transmite tu se\u00f1al sin degradaci\u00f3n<\/li>\n<li>Chaqueta exterior resistente pero flexible<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Con su cableado robusto de calibre 14 y su cubierta exterior robusta, el cable de altavoz BOSS BSC-5 te servir\u00e1 bien durante a\u00f1os. Tu tono de guitarra o bajo llegar\u00e1 a su destino sin perder fidelidad. Tanto si tocas un amplificador BOSS como si no, cuando llega el momento de conectar la cabeza del amplificador a la caja de altavoces, Sweetwater puede recomendarte con confianza el BOSS BSC-5.<\/p>\n","protected":false},"featured_media":34952,"template":"","meta":[],"pwb-brand":[93],"product_brand":[],"product_cat":[145,150],"product_tag":[5459],"class_list":["post-34951","product","type-product","status-publish","has-post-thumbnail","pwb-brand-boss","product_cat-accesorios","product_cat-cables","product_tag-novedades030326","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cable de altavoz Boss BSC-5 - 1,5M - Music Hall<\/title>\n<meta name=\"description\" content=\"Con su cableado robusto de calibre 14 y su cubierta exterior robusta, el cable de altavoz BOSS BSC-5 te servir\u00e1 bien durante a\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cable de altavoz Boss BSC-5 - 1,5M - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Con su cableado robusto de calibre 14 y su cubierta exterior robusta, el cable de altavoz BOSS BSC-5 te servir\u00e1 bien durante a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/BSC-5E.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1372\" \/>\n\t<meta property=\"og:image:height\" content=\"1372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cable de altavoz Boss BSC-5 - 1,5M - Music Hall","description":"Con su cableado robusto de calibre 14 y su cubierta exterior robusta, el cable de altavoz BOSS BSC-5 te servir\u00e1 bien durante a\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/","og_locale":"es_ES","og_type":"article","og_title":"Cable de altavoz Boss BSC-5 - 1,5M - Music Hall","og_description":"Con su cableado robusto de calibre 14 y su cubierta exterior robusta, el cable de altavoz BOSS BSC-5 te servir\u00e1 bien durante a\u00f1os.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-09-01T14:25:21+00:00","og_image":[{"width":1372,"height":1372,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/BSC-5E.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/","name":"Cable de altavoz Boss BSC-5 - 1,5M - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/BSC-5E.webp","datePublished":"2026-03-06T13:27:05+00:00","dateModified":"2026-09-01T14:25:21+00:00","description":"Con su cableado robusto de calibre 14 y su cubierta exterior robusta, el cable de altavoz BOSS BSC-5 te servir\u00e1 bien durante a\u00f1os.","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/BSC-5E.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/BSC-5E.webp","width":1372,"height":1372},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/cable-de-altavoz-boss-bsc-5-15m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Cable de altavoz Boss BSC-5 &#8211; 1,5M"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":93,"name":"Boss","slug":"boss"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/34951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/34952"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=34951"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=34951"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=34951"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=34951"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=34951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}