{"id":35005,"date":"2026-03-06T15:49:52","date_gmt":"2026-03-06T18:49:52","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=35005"},"modified":"2026-07-08T09:43:42","modified_gmt":"2026-07-08T12:43:42","slug":"amplificador-de-instalacion-mz-140dx-hh","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/","title":{"rendered":"Amplificador de instalaci\u00f3n MZ-140DX HH"},"content":{"rendered":"<p>Equipado con dos conectores Euroblock balanceados de entrada de 3,5 mm, el MZ-140DX ofrece flexibilidad en la asignaci\u00f3n de entradas, permitiendo al usuario asignar entradas 1:1 o 1:Todo. El sencillo panel de control simplifica la configuraci\u00f3n y el funcionamiento, con tiras frontales de &#8216;garabato&#8217; que ofrecen una forma c\u00f3moda para que los instaladores etiqueten e identifiquen los canales de salida.<\/p>\n<p>Por primera vez en la serie MZ, hemos incluido la opci\u00f3n de usar la entrada USB C en el panel trasero para transmitir audio compatible con la clase a 48kHz. Tambi\u00e9n hemos desarrollado una aplicaci\u00f3n de escritorio completamente nueva que permite una personalizaci\u00f3n profunda del MZ-140DX. La aplicaci\u00f3n MZ-Control ofrece al instalador la capacidad de controlar una amplia gama de par\u00e1metros, incluyendo sensibilidad de entrada, HPF, retardo, fase, ecualizador, compresi\u00f3n, enrutamiento de entrada, cruce y limitador. Esto abre un mundo de personalizaci\u00f3n nunca visto en los modelos MZ y permite al instalador integrar un sistema de audio hecho a medida para la aplicaci\u00f3n.<\/p>\n<p>El formato compacto de media rack de 1U del MZ-140DX lo convierte en una elecci\u00f3n perfecta para su instalaci\u00f3n en espacios reducidos, con hardware incluido para montar la unidad en superficie o para conectar dos unidades lado a lado en un rack de 1U de 19 pulgadas. El MZ-140DX te ofrece todo lo que necesitas desde un amplificador compacto de instalaci\u00f3n en un sistema peque\u00f1o, pero aun as\u00ed ha sido dise\u00f1ado pensando en la expansi\u00f3n del sistema. El MZ-140DX es el complemento perfecto para el controlador de zonas y el preamplificador MZ-64P, ofreci\u00e9ndote mayor destreza con opciones de entrada ampliadas, la posibilidad de a\u00f1adir controladores de pared MZ-C2 a tu sistema, entrada de anulaci\u00f3n de emergencia y entrada de paginaci\u00f3n manual, todo lo cual es f\u00e1cil de configurar y controlar.<\/p>\n<h2 class=\"border-left my-4\">Caracter\u00edsticas<\/h2>\n<ul class=\"grid grid-cols-1 md:grid-cols-2 gap-x-2\">\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Dimensiones de la unidad (Hwd)<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">44 x 265 x 345 mm, (1,7&#8243; x 10,4&#8243; x 13,6&#8243;)<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Tipo de sistema<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Amplificador de Zona de Instalaci\u00f3n de 2 Canales<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Entradas<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Anal\u00f3gico &#8211; 2 conectores Euroblock balanceados de 3,5 mm. Digital &#8211; Streaming de audio compatible con la clase C USB @ 48kHz.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Salidas<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">2 (Puede accionar directamente sistemas de 4 ohmios, 8 ohmios o 70\/100V seleccionables por salida).<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Energ\u00eda<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Potencia total del sistema &#8211; 280W. Potencia por canal de salida @ 4\/8 ohmios &#8211; 140W RMS* 140W en 8 ohmios. 95W a 4ohmios. (*130W m\u00e1ximo cuando funciono a 120V de tensi\u00f3n de red). Potencia por canal de salida @ 70\/100V &#8211; 140W RMS* 140W a 70V. 120W a 100V (*m\u00e1ximo 130W cuando se usa a 120V de tensi\u00f3n de red).<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Impedancia<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Impedancia m\u00ednima de transmisi\u00f3n &#8211; 4 ohmios<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Limitador de pico de salida<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">S\u00ed (configurable por el usuario mediante la aplicaci\u00f3n MZ-CTRL).<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Respuesta en frecuencia<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">20-20 prensas oto\u00f1ales \u00b10,1 prensas (modo suelto) 80-20 prensas oto\u00f1ales \u00b10,1 prensas (modo suelto).<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Sensibilidad de entrada<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Canal 1 y 2 &#8211; L\u00ednea 0dBu nominal.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Impedancia de entrada (Bal\/Unbal)<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Entrada de l\u00ednea: 20K\u03a9.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">THD+N<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">&lt;0,01% @ 0dBu de entrada, volumen medio &lt;0,008% @ +6dBu de entrada, volumen m\u00e1ximo.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Diafon\u00eda<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">&lt; -95 dB de diafon\u00eda entre canales, volumen m\u00e1ximo.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Fondo de ruido<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">&lt; -70dBu (sin silenciar) &lt; -110dBu (silenciado).<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Relaci\u00f3n se\u00f1al-ruido ponderada A<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">&gt;110dB.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Refrigeraci\u00f3n<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Ventiladores de doble rodamiento sin escobillas de bajo ruido de 40&#215;20 mm con control t\u00e9rmico para un rendimiento fiable a altas temperaturas ambientales.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Conector de salida<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Conectores Euroblock de 5,08 mm por zona.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Controles<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Cada salida de amplificador cuenta con controles maestros de volumen y Led de Doble Funci\u00f3n de Se\u00f1al Presente\/Clip. El panel trasero incluye opciones de bloqueo del panel frontal y modo amplificador de zonas mediante interruptores dip.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">EQ<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Disponible en la aplicaci\u00f3n MZ-CTRL.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Indicadores<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">En Power\/Standby, todas las salidas cuentan con LEDs de se\u00f1al presente y clips de amplificador.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Alimentaci\u00f3n de CA<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Universal AC 100-240V~ 50\/60HZ.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Consumo de energ\u00eda<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">17W en ralent\u00ed, 150W en lo habitual, 200W como m\u00e1ximo, 0,4W en espera.<\/div>\n<\/li>\n<li class=\"grid grid-cols-3\">\n<div class=\" bg-grey-700 text-white border-b border-white p-2 flex items-center heavy\">Accesorios<\/div>\n<div class=\"col-span-2 bg-white p-2 border-b border-black flex items-center\">Kit de montaje en rack incluido. Incluidos 4 Euroblocks de 3,5 mm de 3 v\u00edas, 2 de 3,5 mm de 5 v\u00edas, 1 de 5,08 mm de 6 v\u00edas incluidos.<\/div>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El MZ-140DX es un amplificador de instalaci\u00f3n compacto pero vers\u00e1til de 2 canales dise\u00f1ado para instalaciones m\u00e1s peque\u00f1as o para ampliar un sistema de mayor tama\u00f1o. El MZ-140DX entrega 140W RMS por canal con una potencia total del sistema de 280W RMS, asegurando un rendimiento fiable y constante. La asignaci\u00f3n din\u00e1mica de potencia del MZ-140DX permite que el canal 1 consuma hasta los 280W RMS completos de potencia disponible, si es necesario, siempre que no se supere la potencia total del sistema. Esto permite al MZ-140DX proporcionar una gesti\u00f3n eficiente de la energ\u00eda adaptada de forma \u00fanica a cada sistema. El MZ-140DX ofrece flexibilidad para una amplia gama de aplicaciones, soportando tanto sistemas de 70\/100V (Hi-Z) como de 4\/8ohm (Lo-Z).<\/p>\n","protected":false},"featured_media":35009,"template":"","meta":[],"pwb-brand":[5145],"product_brand":[],"product_cat":[5383],"product_tag":[5459],"class_list":["post-35005","product","type-product","status-publish","has-post-thumbnail","pwb-brand-hh","product_cat-amplificador-de-instalaciones","product_tag-novedades030326","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amplificador de instalaci\u00f3n MZ-140DX HH - Music Hall<\/title>\n<meta name=\"description\" content=\"El PA\u00a0 450.5 de SKP es un amplificador profesional dise\u00f1ado especialmente para instalaciones de sonido en entornos comerciales y profesionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amplificador de instalaci\u00f3n MZ-140DX HH - Music Hall\" \/>\n<meta property=\"og:description\" content=\"El PA\u00a0 450.5 de SKP es un amplificador profesional dise\u00f1ado especialmente para instalaciones de sonido en entornos comerciales y profesionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:43:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/MZ-140DXE.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amplificador de instalaci\u00f3n MZ-140DX HH - Music Hall","description":"El PA\u00a0 450.5 de SKP es un amplificador profesional dise\u00f1ado especialmente para instalaciones de sonido en entornos comerciales y profesionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/","og_locale":"es_ES","og_type":"article","og_title":"Amplificador de instalaci\u00f3n MZ-140DX HH - Music Hall","og_description":"El PA\u00a0 450.5 de SKP es un amplificador profesional dise\u00f1ado especialmente para instalaciones de sonido en entornos comerciales y profesionales.","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:43:42+00:00","og_image":[{"width":1067,"height":1067,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/MZ-140DXE.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/","name":"Amplificador de instalaci\u00f3n MZ-140DX HH - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/MZ-140DXE.webp","datePublished":"2026-03-06T18:49:52+00:00","dateModified":"2026-07-08T12:43:42+00:00","description":"El PA\u00a0 450.5 de SKP es un amplificador profesional dise\u00f1ado especialmente para instalaciones de sonido en entornos comerciales y profesionales.","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/MZ-140DXE.webp","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2026\/03\/MZ-140DXE.webp","width":1067,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/amplificador-de-instalacion-mz-140dx-hh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Amplificador de instalaci\u00f3n MZ-140DX HH"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":5145,"name":"HH","slug":"hh"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/35005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/35009"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=35005"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=35005"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=35005"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=35005"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=35005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}