{"id":8468,"date":"2021-07-24T08:54:03","date_gmt":"2021-07-24T12:54:03","guid":{"rendered":"https:\/\/musichall.com.py\/tienda\/?post_type=product&#038;p=8468"},"modified":"2026-07-08T09:41:09","modified_gmt":"2026-07-08T12:41:09","slug":"sistema-de-altavoz-yamaha-vxl1b-16","status":"publish","type":"product","link":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/","title":{"rendered":"Sistema de Altavoz Yamaha VXL1B-16"},"content":{"rendered":"<p>Altavoz de matriz de l\u00ednea delgada con controladores de 16 x 1,5 \u201d<\/p>\n<p>Los altavoces de arreglo en l\u00ednea de la serie VXL ofrecen una combinaci\u00f3n \u00fanica de excelente calidad de sonido y forma delgada que es ideal para una variedad de entornos.<\/p>\n<p>Los altavoces line array ofrecen una proyecci\u00f3n excelente, as\u00ed como un volumen y una calidad de sonido uniformes en una amplia \u00e1rea de servicio, lo que los convierte en una excelente opci\u00f3n para salas de usos m\u00faltiples, salas de conferencias, salas de conferencias y otras instalaciones que requieren la m\u00e1xima inteligibilidad en toda el \u00e1rea de escucha.<\/p>\n<p>La serie VXL1 incluye tres modelos con diferentes n\u00fameros de unidades de altavoz.\u00a0Los modelos se pueden combinar para servir de manera \u00f3ptima a una variedad de espacios y situaciones.<\/p>\n<p>Los gabinetes delgados de 54 mil\u00edmetros de ancho y los dise\u00f1os de rejilla elegantemente curvados combinan a la perfecci\u00f3n con cualquier decoraci\u00f3n mientras brindan un sonido uniforme y de alta calidad para la reproducci\u00f3n de voz y m\u00fasica en una amplia gama de aplicaciones.<\/p>\n<p>Principales caracter\u00edsticas:<\/p>\n<p style=\"text-align: left;\">Unidades de altavoz de rango completo de 1,5 pulgadas (3,75 cm) con imanes de neodimio<br \/>\nAmplia dispersi\u00f3n horizontal para un SPL uniforme en un \u00e1rea amplia<br \/>\nLa cobertura vertical se puede seleccionar entre dos modos, Normal y Ancho<br \/>\nEl dise\u00f1o delgado complementa cualquier decoraci\u00f3n de interiores<br \/>\nLos recintos se pueden pintar para que coincidan con el entorno<br \/>\nSoporte de montaje en pared incluido<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/M0015pOPlGc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<h2 id=\"d1155608\"><span style=\"color: #555555; font-size: 14.4px;\">Los altavoces en configuraci\u00f3n &#8220;line array&#8221; de la serie VXL ofrecen una combinaci\u00f3n \u00fanica de calidad de sonido sobresaliente con un formato delgado y estilizado que resulta ideal para una gran variedad de entornos.<\/span><\/h2>\n<div class=\"clearfix\">\n<p>Los altavoces en configuraci\u00f3n &#8220;line array&#8221; ofrecen una proyecci\u00f3n excelente, as\u00ed como uniformidad de volumen y calidad de sonido sobre un \u00e1rea de alcance bastante amplia, lo que los convierte en una gran elecci\u00f3n para salas multifunci\u00f3n, aulas grandes, salas de conferencias y otras instalaciones donde se requiera m\u00e1xima inteligibilidad en todo el \u00e1rea de escucha.<\/p>\n<p>La serie VXL incluye tres modelos con diferente n\u00famero de unidades de altavoces. Los modelos se pueden combinar para abarcar de forma \u00f3ptima una gran variedad de espacios y situaciones.<\/p>\n<p>Sus cajas estrechas (54 mm de ancho) y sus rejillas elegantemente curvadas combinan a la perfecci\u00f3n con cualquier decoraci\u00f3n de interior a la vez que proporcionan un sonido uniforme y de alta calidad para las intervenciones habladas y la reproducci\u00f3n de m\u00fasica en muchos tipos de aplicaciones.<\/p>\n<\/div>\n<p>2PARYAVXL1B16T<\/p>\n","protected":false},"featured_media":8469,"template":"","meta":[],"pwb-brand":[72],"product_brand":[],"product_cat":[81,269],"product_tag":[2283,845,2281,2282,84],"class_list":["post-8468","product","type-product","status-publish","has-post-thumbnail","pwb-brand-yamaha","product_cat-audio","product_cat-receptores","product_tag-sistema-de-altavoz","product_tag-subwoofer","product_tag-vxl1b-16","product_tag-vxl1b16","product_tag-yamaha","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistema de Altavoz Yamaha VXL1B-16 - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema de Altavoz Yamaha VXL1B-16 - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Los altavoces en configuraci\u00f3n &quot;line array&quot; de la serie VXL ofrecen una combinaci\u00f3n \u00fanica de calidad de sonido sobresaliente con un formato delgado y estilizado que resulta ideal para una gran variedad de entornos.   Los altavoces en configuraci\u00f3n &quot;line array&quot; ofrecen una proyecci\u00f3n excelente, as\u00ed como uniformidad de volumen y calidad de sonido sobre un \u00e1rea de alcance bastante amplia, lo que los convierte en una gran elecci\u00f3n para salas multifunci\u00f3n, aulas grandes, salas de conferencias y otras instalaciones donde se requiera m\u00e1xima inteligibilidad en todo el \u00e1rea de escucha.  La serie VXL incluye tres modelos con diferente n\u00famero de unidades de altavoces. Los modelos se pueden combinar para abarcar de forma \u00f3ptima una gran variedad de espacios y situaciones.  Sus cajas estrechas (54 mm de ancho) y sus rejillas elegantemente curvadas combinan a la perfecci\u00f3n con cualquier decoraci\u00f3n de interior a la vez que proporcionan un sonido uniforme y de alta calidad para las intervenciones habladas y la reproducci\u00f3n de m\u00fasica en muchos tipos de aplicaciones.   2PARYAVXL1B16T\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MusicHallPY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:41:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2021\/07\/2PARYAVXL1B16T.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema de Altavoz Yamaha VXL1B-16 - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/","og_locale":"es_ES","og_type":"article","og_title":"Sistema de Altavoz Yamaha VXL1B-16 - Music Hall","og_description":"Los altavoces en configuraci\u00f3n \"line array\" de la serie VXL ofrecen una combinaci\u00f3n \u00fanica de calidad de sonido sobresaliente con un formato delgado y estilizado que resulta ideal para una gran variedad de entornos.   Los altavoces en configuraci\u00f3n \"line array\" ofrecen una proyecci\u00f3n excelente, as\u00ed como uniformidad de volumen y calidad de sonido sobre un \u00e1rea de alcance bastante amplia, lo que los convierte en una gran elecci\u00f3n para salas multifunci\u00f3n, aulas grandes, salas de conferencias y otras instalaciones donde se requiera m\u00e1xima inteligibilidad en todo el \u00e1rea de escucha.  La serie VXL incluye tres modelos con diferente n\u00famero de unidades de altavoces. Los modelos se pueden combinar para abarcar de forma \u00f3ptima una gran variedad de espacios y situaciones.  Sus cajas estrechas (54 mm de ancho) y sus rejillas elegantemente curvadas combinan a la perfecci\u00f3n con cualquier decoraci\u00f3n de interior a la vez que proporcionan un sonido uniforme y de alta calidad para las intervenciones habladas y la reproducci\u00f3n de m\u00fasica en muchos tipos de aplicaciones.   2PARYAVXL1B16T","og_url":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/","og_site_name":"Music Hall","article_publisher":"https:\/\/www.facebook.com\/MusicHallPY","article_modified_time":"2026-07-08T12:41:09+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2021\/07\/2PARYAVXL1B16T.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/","url":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/","name":"Sistema de Altavoz Yamaha VXL1B-16 - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/#primaryimage"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/#primaryimage"},"thumbnailUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2021\/07\/2PARYAVXL1B16T.jpg","datePublished":"2021-07-24T12:54:03+00:00","dateModified":"2026-07-08T12:41:09+00:00","breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/#primaryimage","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2021\/07\/2PARYAVXL1B16T.jpg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2021\/07\/2PARYAVXL1B16T.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/producto\/sistema-de-altavoz-yamaha-vxl1b-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/musichall.com.py\/tienda\/shop\/"},{"@type":"ListItem","position":3,"name":"Sistema de Altavoz Yamaha VXL1B-16"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"brands":[{"id":72,"name":"Yamaha","slug":"yamaha"}],"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product\/8468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media\/8469"}],"wp:attachment":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/media?parent=8468"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/pwb-brand?post=8468"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_brand?post=8468"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat?post=8468"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_tag?post=8468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}