{"id":269,"count":96,"description":"Compr\u00e1 Home Theater \/ Cine en Casa en Paraguay\r\nLos mejores equipos de audio para cine en casa los encontras en Music Hall.\r\nAtenci\u00f3n personalizada y servicio de instalaci\u00f3n a medida","link":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/","name":"Home Theater","slug":"receptores","taxonomy":"product_cat","parent":81,"meta":[],"menu_order":23,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home Theater - Music Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home Theater - Music Hall\" \/>\n<meta property=\"og:description\" content=\"Compr\u00e1 Home Theater \/ Cine en Casa en Paraguay Los mejores equipos de audio para cine en casa los encontras en Music Hall. Atenci\u00f3n personalizada y servicio de instalaci\u00f3n a medida\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Hall\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/07\/logo_bannermh.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicHallPY\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home Theater - Music Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/","og_locale":"es_ES","og_type":"article","og_title":"Home Theater - Music Hall","og_description":"Compr\u00e1 Home Theater \/ Cine en Casa en Paraguay Los mejores equipos de audio para cine en casa los encontras en Music Hall. Atenci\u00f3n personalizada y servicio de instalaci\u00f3n a medida","og_url":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/","og_site_name":"Music Hall","og_image":[{"width":1200,"height":675,"url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2025\/07\/logo_bannermh.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicHallPY","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/","url":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/","name":"Home Theater - Music Hall","isPartOf":{"@id":"https:\/\/musichall.com.py\/tienda\/#website"},"breadcrumb":{"@id":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/receptores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musichall.com.py\/tienda\/"},{"@type":"ListItem","position":2,"name":"Audio","item":"https:\/\/musichall.com.py\/tienda\/categoria-producto\/audio\/"},{"@type":"ListItem","position":3,"name":"Home Theater"}]},{"@type":"WebSite","@id":"https:\/\/musichall.com.py\/tienda\/#website","url":"https:\/\/musichall.com.py\/tienda\/","name":"Music Hall - Instrumentos Musicales","description":"Instrumentos Musicales - Audio Profesional - Instalaciones","publisher":{"@id":"https:\/\/musichall.com.py\/tienda\/#organization"},"alternateName":"Music Hall Paraguay - Instrumentos Musicales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musichall.com.py\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musichall.com.py\/tienda\/#organization","name":"Music Hall","url":"https:\/\/musichall.com.py\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","contentUrl":"https:\/\/musichall.com.py\/tienda\/wp-content\/uploads\/2020\/09\/mh_logo.svg","width":1,"height":1,"caption":"Music Hall"},"image":{"@id":"https:\/\/musichall.com.py\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MusicHallPY","https:\/\/x.com\/MusicHallPY","https:\/\/www.instagram.com\/musichallpy\/","https:\/\/www.youtube.com\/musichalltv"]}]}},"_links":{"self":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat\/269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product_cat\/81"}],"wp:post_type":[{"href":"https:\/\/musichall.com.py\/tienda\/wp-json\/wp\/v2\/product?product_cat=269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}